{"id":9178,"date":"2014-10-17T10:39:46","date_gmt":"2014-10-17T09:39:46","guid":{"rendered":"http:\/\/blog.cofb.cat\/?p=9178"},"modified":"2014-10-17T10:39:46","modified_gmt":"2014-10-17T09:39:46","slug":"plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola","status":"publish","type":"post","link":"https:\/\/www.cofb.org\/es\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/","title":{"rendered":"Plenufar 5: las mujeres en edad climat\u00e9rica en Catalu\u00f1a consumen m\u00e1s boller\u00eda pero menos tabaco que la media espa\u00f1ola"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-8467 alignleft\" alt=\"Plenufarcat\" src=\"http:\/\/blog.cofb.cat\/wp-content\/uploads\/2014\/09\/Plenufarcat2.jpg\" width=\"247\" height=\"348\" \/>El 18 de octubre se celebra el <b>D\u00eda Mundial de la Menopausia<\/b>, una etapa que es objeto de diferentes estudios, entre ellos uno que han realizado las farmacias llamado \u201c<span style=\"text-decoration: underline;\"><a href=\"http:\/\/blog.cofb.cat\/farmacies-de-barcelona-ajuden-a-millorar-la-qualitat-de-vida-de-les-dones-amb-menopausa-en-el-marc-de-la-campanya-plenufar-v\/\">Educaci\u00f3n nutricional en la menopausia<\/a><\/span>\u201d. Un total de 2.500 farmacias en Espa\u00f1a, de las que m\u00e1s de 300 han sido catalanas, han participado en esta investigaci\u00f3n que concluye, entre otras cosas, que las mujeres <b>en Catalu\u00f1a consumen cerca de un 10% m\u00e1s de boller\u00eda y reposter\u00eda industrial<\/b> (56,4%) que la media espa\u00f1ola (46,6%). Se han encuestado a 9.000 mujeres, de las que 1.382 han sido catalanas y 1.053 barcelonesas.<\/p>\n<p><div class=\"box shadow\">Algunos resultados destacables de esta iniciativa, que ha sido impulsada por el Consejo General de Colegios de Farmac\u00e9uticos y se ha llevado a cabo con la colaboraci\u00f3n de la vocal\u00eda de Alimentaci\u00f3n del Colegio de Farmac\u00e9uticos de Barcelona:<\/p>\n<ul>\n<li><b>Las mujeres catalanas, menos fumadoras que la media espa\u00f1ola<\/b>: en Catalu\u00f1a hay un 17,8% de fumadoras, cuando la media espa\u00f1ola se encuentra en el 21,4%; y tambi\u00e9n existen diferencias en el n\u00famero de ex fumadoras: un 31% en Catalu\u00f1a respecto al 25,9% de Espa\u00f1a.<\/li>\n<li>En cuanto a la adherencia a la dieta mediterr\u00e1nea, los resultados son similares a los espa\u00f1oles, y concretamente a Catalu\u00f1a, <b>habr\u00eda que comer m\u00e1s fruta y legumbres<\/b>.<\/li>\n<li>Se mantiene al mismo nivel en el consumo global de suplementos y complementos nutricionales, a excepci\u00f3n del <b>consumo de plantas medicinales y homeopat\u00eda<\/b>, ya que Catalu\u00f1a <b>supera la media con m\u00e1s de un 6%<\/b>.<\/div><\/li>\n<\/ul>\n<p>Un reciente estudio del Instituto M\u00e9dico Europeo de la Obesidad ha estimado <b>que las mujeres podr\u00edan aumentar hasta 10kg durante la perimenopausia<\/b> \u2013etapa previa a la menopausia\u2013 si no llevan una alimentaci\u00f3n adecuada y h\u00e1bitos saludables. Algunas recomendaciones para prevenirlo:<\/p>\n<ul>\n<li>Anna Bach, vocal de Alimentaci\u00f3n y Nutrici\u00f3n: incluir en la dieta, entre otros, alimentos ricos en fibra, ya que ayudan a controlar el peso y disminuyen el riesgo de la enfermedad cardiovascular, as\u00ed como pescado azul y frutos secos ( ricos en \u00e1cidos grasos (Omega-3) que favorecen a la salud cardiovascular, articular y cerebral.<\/li>\n<li>Mar\u00eda Jos\u00e9 Alonso, vocal de Plantas Medicinales y Homeopat\u00eda: realizar ejercicio f\u00edsico moderado, pero diario; evitar el tabaco y las bebidas alcoh\u00f3licas y asegurar una buena hidrataci\u00f3n, puesto que son h\u00e1bitos saludables que garantizan el bienestar de la mujer menop\u00e1usica.<\/li>\n<\/ul>\n<p><span style=\"color: #808080;\"><b>Para m\u00e1s recomendaciones para una buena salud durante la menopausia, desc\u00e1rgate este <span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.portalfarma.com\/Profesionales\/campanaspf\/categorias\/Documents\/Documentos%20Publica\/2013-Folleto-Plenufar-5-catalan.pdf\"><span style=\"color: #808080; text-decoration: underline;\">folleto de la campa\u00f1a<\/span><\/a><\/span><\/b><\/span><\/p>\n<figure id=\"attachment_9202\" aria-describedby=\"caption-attachment-9202\" style=\"width: 320px\" class=\"wp-caption alignright\"><a href=\"http:\/\/blog.cofb.cat\/wp-content\/uploads\/2014\/10\/actereialacademia.jpg\"><img decoding=\"async\" class=\"wp-image-9202\" alt=\"actereialacademia\" src=\"http:\/\/blog.cofb.cat\/wp-content\/uploads\/2014\/10\/actereialacademia.jpg\" width=\"320\" height=\"274\" \/><\/a><figcaption id=\"caption-attachment-9202\" class=\"wp-caption-text\">Garc\u00eda, Rivero, Bach y Alonso en la presentaci\u00f3n de la Real Academia de Farmacia<\/figcaption><\/figure>\n<p>El estudio, enmarcado en la quinta edici\u00f3n del Plan de Educaci\u00f3n Nutricional por el Farmac\u00e9utico (Plenufar), se present\u00f3 institucionalmente el 29 de septiembre en la Real Academia de Farmacia (RAFC) en un acto organizado por la Secci\u00f3n segunda Ciencias Biol\u00f3gicas y Biotecnolog\u00eda . Intervinieron Montserrat Rivero, ex-vocal nacional de Alimentaci\u00f3n del CGCOF y del COFB y Acad\u00e9mica Numeraria de la RAFC, exponiendo cu\u00e1les son las campa\u00f1as farmac\u00e9uticas de educaci\u00f3n nutricional; Aquilino Garc\u00eda, vocal nacional de Alimentaci\u00f3n, argumentando la importancia social y sanitaria de las campa\u00f1as farmac\u00e9uticas de alimentaci\u00f3n, y Mar\u00eda Jos\u00e9 Alonso, vocal de Plantas Medicinales del Colegio, explicando los resultados de la campa\u00f1a Plenufar 5.<\/p>\n<p><i><br \/>\nM\u00e1s informaci\u00f3n sobre la campa\u00f1a \u201c<\/i><i>Educaci\u00f3n Nutricional en la menopausia\u201d en su<\/i><i>\u00a0<span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.acvglobal.com\/plenufar5\/\">p\u00e1gina web<\/a>.<\/span><br \/>\n<\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>El 18 de octubre se celebra el D\u00eda Mundial de la Menopausia, una etapa que es objeto de diferentes estudios, entre ellos uno que han realizado las farmacias llamado \u201cEducaci\u00f3n nutricional en la menopausia\u201d. Un total de 2.500 farmacias en Espa\u00f1a, de las cuales m\u00e1s de 300 han sido catalanas, [...]<\/p>","protected":false},"author":1,"featured_media":9217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[32],"tags":[16,76],"class_list":["post-9178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies-farmacia","tag-alimentacio-i-nutricio","tag-oficina-de-farmacia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plenufar 5: les dones en edat climat\u00e8rica a Catalunya consumeixen m\u00e9s brioxeria per\u00f2 menys tabac que la mitjana espanyola - Col\u00b7legi de Farmac\u00e8utics de Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plenufar 5: les dones en edat climat\u00e8rica a Catalunya consumeixen m\u00e9s brioxeria per\u00f2 menys tabac que la mitjana espanyola - Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"og:description\" content=\"El 18 d\u2019octubre se celebra el Dia Mundial de la Menopausa, una etapa que \u00e9s objecte de diferents estudis, entre ells un que han realitzat les farm\u00e0cies anomenat \u201cEducaci\u00f3 nutricional en la menopausa\u201d. Un total de 2.500 farm\u00e0cies a Espanya, de les quals m\u00e9s de 300 han estat catalanes, han [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-17T09:39:46+00:00\" \/>\n<meta name=\"author\" content=\"wpAdminCofbOrg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:site\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpAdminCofbOrg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/\"},\"author\":{\"name\":\"wpAdminCofbOrg\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\"},\"headline\":\"Plenufar 5: les dones en edat climat\u00e8rica a Catalunya consumeixen m\u00e9s brioxeria per\u00f2 menys tabac que la mitjana espanyola\",\"datePublished\":\"2014-10-17T09:39:46+00:00\",\"dateModified\":\"2014-10-17T09:39:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/\"},\"wordCount\":591,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Alimentaci\u00f3 i nutrici\u00f3\",\"Oficina de farm\u00e0cia\"],\"articleSection\":[\"Not\u00edcies farm\u00e0cia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/\",\"url\":\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/\",\"name\":\"Plenufar 5: les dones en edat climat\u00e8rica a Catalunya consumeixen m\u00e9s brioxeria per\u00f2 menys tabac que la mitjana espanyola - Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.cofb.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2014-10-17T09:39:46+00:00\",\"dateModified\":\"2014-10-17T09:39:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.cofb.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plenufar 5: les dones en edat climat\u00e8rica a Catalunya consumeixen m\u00e9s brioxeria per\u00f2 menys tabac que la mitjana espanyola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cofb.org\/#website\",\"url\":\"https:\/\/www.cofb.org\/\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cofb.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cofb.org\/#organization\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"url\":\"https:\/\/www.cofb.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"contentUrl\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"width\":500,\"height\":105,\"caption\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\"},\"image\":{\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\",\"https:\/\/twitter.com\/farmaceuticsbcn\",\"https:\/\/www.instagram.com\/farmaceuticsbcn\/\",\"https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\",\"name\":\"wpAdminCofbOrg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"caption\":\"wpAdminCofbOrg\"},\"sameAs\":[\"http:\/\/192.168.64.122\/wordpress\"],\"url\":\"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plenufar 5: les dones en edat climat\u00e8rica a Catalunya consumeixen m\u00e9s brioxeria per\u00f2 menys tabac que la mitjana espanyola - Col\u00b7legi de Farmac\u00e8utics de Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/","og_locale":"es_ES","og_type":"article","og_title":"Plenufar 5: les dones en edat climat\u00e8rica a Catalunya consumeixen m\u00e9s brioxeria per\u00f2 menys tabac que la mitjana espanyola - Col\u00b7legi de Farmac\u00e8utics de Barcelona","og_description":"El 18 d\u2019octubre se celebra el Dia Mundial de la Menopausa, una etapa que \u00e9s objecte de diferents estudis, entre ells un que han realitzat les farm\u00e0cies anomenat \u201cEducaci\u00f3 nutricional en la menopausa\u201d. Un total de 2.500 farm\u00e0cies a Espanya, de les quals m\u00e9s de 300 han estat catalanes, han [&hellip;]","og_url":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/","og_site_name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","article_publisher":"https:\/\/www.facebook.com\/farmaceuticsbcn\/","article_published_time":"2014-10-17T09:39:46+00:00","author":"wpAdminCofbOrg","twitter_card":"summary_large_image","twitter_creator":"@farmaceuticsbcn","twitter_site":"@farmaceuticsbcn","twitter_misc":{"Escrito por":"wpAdminCofbOrg","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#article","isPartOf":{"@id":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/"},"author":{"name":"wpAdminCofbOrg","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb"},"headline":"Plenufar 5: les dones en edat climat\u00e8rica a Catalunya consumeixen m\u00e9s brioxeria per\u00f2 menys tabac que la mitjana espanyola","datePublished":"2014-10-17T09:39:46+00:00","dateModified":"2014-10-17T09:39:46+00:00","mainEntityOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/"},"wordCount":591,"commentCount":0,"publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"image":{"@id":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#primaryimage"},"thumbnailUrl":"","keywords":["Alimentaci\u00f3 i nutrici\u00f3","Oficina de farm\u00e0cia"],"articleSection":["Not\u00edcies farm\u00e0cia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/","url":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/","name":"Plenufar 5: les dones en edat climat\u00e8rica a Catalunya consumeixen m\u00e9s brioxeria per\u00f2 menys tabac que la mitjana espanyola - Col\u00b7legi de Farmac\u00e8utics de Barcelona","isPartOf":{"@id":"https:\/\/www.cofb.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#primaryimage"},"image":{"@id":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#primaryimage"},"thumbnailUrl":"","datePublished":"2014-10-17T09:39:46+00:00","dateModified":"2014-10-17T09:39:46+00:00","breadcrumb":{"@id":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/novaorg.cofb.net\/2014\/10\/17\/plenufar-5-les-dones-en-edat-climaterica-a-catalunya-consumeixen-mes-brioxeria-pero-menys-tabac-que-la-mitjana-espanyola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cofb.org\/"},{"@type":"ListItem","position":2,"name":"Plenufar 5: les dones en edat climat\u00e8rica a Catalunya consumeixen m\u00e9s brioxeria per\u00f2 menys tabac que la mitjana espanyola"}]},{"@type":"WebSite","@id":"https:\/\/www.cofb.org\/#website","url":"https:\/\/www.cofb.org\/","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","description":"","publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cofb.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cofb.org\/#organization","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","url":"https:\/\/www.cofb.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","contentUrl":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","width":500,"height":105,"caption":"Col\u00b7legi de Farmac\u00e8utics de Barcelona"},"image":{"@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/farmaceuticsbcn\/","https:\/\/twitter.com\/farmaceuticsbcn","https:\/\/www.instagram.com\/farmaceuticsbcn\/","https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/"]},{"@type":"Person","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb","name":"wpAdminCofbOrg","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","caption":"wpAdminCofbOrg"},"sameAs":["http:\/\/192.168.64.122\/wordpress"],"url":"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"wpAdminCofbOrg","author_link":"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/"},"uagb_comment_info":0,"uagb_excerpt":"El 18 d\u2019octubre se celebra el Dia Mundial de la Menopausa, una etapa que \u00e9s objecte de diferents estudis, entre ells un que han realitzat les farm\u00e0cies anomenat \u201cEducaci\u00f3 nutricional en la menopausa\u201d. Un total de 2.500 farm\u00e0cies a Espanya, de les quals m\u00e9s de 300 han estat catalanes, han [&hellip;]","_links":{"self":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts\/9178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/comments?post=9178"}],"version-history":[{"count":0,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts\/9178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/media?parent=9178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/categories?post=9178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/tags?post=9178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}