{"id":77308,"date":"2017-06-19T12:52:00","date_gmt":"2017-06-19T12:52:00","guid":{"rendered":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/"},"modified":"2017-06-19T12:52:00","modified_gmt":"2017-06-19T12:52:00","slug":"farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles","status":"publish","type":"post","link":"https:\/\/www.cofb.org\/es\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/","title":{"rendered":"Farmac\u00e9uticos catalanes se forman para participar en la red de farmacias centinelas"},"content":{"rendered":"<p>\u00a0<\/p>\n<p><i><br \/><\/i><\/p>\n<ul>\n<li><strong>La formaci\u00f3n tuvo lugar la semana pasada en el Colegio de Farmac\u00e9uticos de Barcelona, con conexi\u00f3n para webinar en las sedes de los COFs de Girona, Lleida y Tarragona<\/strong><\/li>\n<li><strong>Tras el \u00e9xito de la prueba piloto en Barcelona, est\u00e1 previsto que el 1 de julio se inicie la puesta en marcha de la Red Centinela en toda Catalu\u00f1a<\/strong><\/li>\n<li><strong>Forma parte de la estrategia de despliegue del Plan de Salud 2016-2020 <\/strong><br \/>\u00a0<\/li>\n<\/ul>\n<p><i>Barcelona, 19 de junio de 2017<\/i><b> Farmac\u00e9uticos catalanes se formaron la semana pasada para participar en la red de farmacias centinelas. <\/b>Una vez superada la formaci\u00f3n, y <b>despu\u00e9s del \u00e9xito de la prueba piloto<\/b> llevada a cabo en Barcelona, <b>est\u00e1 previsto que el proyecto se inicie el d\u00eda 1 de julio en el resto de Catalu\u00f1a. <span>\u00a0<\/p>\n<p><\/span><\/b><\/p>\n<p class=\"MsoNormal\">En el marco de esta iniciativa, impulsada por el <b>Departamento de Salud de la Generalitat y el Consejo de Colegios Farmac\u00e9uticos de Catalu\u00f1a<\/b>, las farmacias trabajan <b>conjuntamente para aportar informaci\u00f3n sobre incidentes de seguridad relacionados con el uso de los medicamentos -como el seguimiento espec\u00edfico de determinados medicamentos-, para monitorizar su abuso o uso recreativo y para obtener datos que se puedan integrar en sistemas de vigilancia otros profesionales sanitarios. <\/b>Esta informaci\u00f3n de primera mano ayuda a planificar actuaciones espec\u00edficas de mejora en el uso de los medicamentos en Catalu\u00f1a, a trav\u00e9s de estrategias de actuaci\u00f3n coordinadas entre las instituciones sanitarias y colegiales. Asimismo, la constituci\u00f3n de esta red estable de farmacias centinelas permite obtener datos v\u00e1lidos generados por la propia din\u00e1mica asistencial y que pueden integrarse en el sistema de vigilancia epidemiol\u00f3gica, facilitando una respuesta m\u00e1s eficaz de los servicios de salud p\u00fablica. <\/p>\n<p class=\"MsoNormal\"><u><strong>\u00bfEn qu\u00e9 consisti\u00f3 la formaci\u00f3n?<\/strong><\/u><\/p>\n<p class=\"MsoNormal\"><b>Durante la tarde del mi\u00e9rcoles 14 de junio tuvo lugar <\/b>en el Colegio de Farmac\u00e9uticos de Barcelona, con conexi\u00f3n para webinar en las sedes de los COFs de Girona, Lleida y Tarragona,<b> una formaci\u00f3n espec\u00edfica en la que se dieron las herramientas necesarias a los farmac\u00e9uticos para que puedan formar parte de la Red.<\/b> Esta formaci\u00f3n corri\u00f3 a cargo de Pilar Gasc\u00f3n, secretaria del Consejo de Colegios Farmac\u00e9uticos de Catalunya (CCFC); Ma Jos\u00e9 Gaspar, jefe de Servicio de Ordenaci\u00f3n y Calidad Farmac\u00e9utica; Manel Rabanal, jefe de Secci\u00f3n de Vigilancia y Publicidad del Medicamento;  Anna Maria Jambrina, de la Direcci\u00f3n General de Ordenaci\u00f3n Profesional y Regulaci\u00f3n Sanitaria del Departament de Salut; Gloria Cereza, del Centro Auton\u00f3mico de Farmacovigilancia de Catalu\u00f1a; Rafael Guayta-Escolies, director de Proyectos e Investigaci\u00f3n del CCFC; Maria Perell\u00f3, del Centro de Informaci\u00f3n del Medicamento del COFB; Pilar Rius, del Consejo de Colegios de Farmac\u00e9uticos de Catalu\u00f1a; y Gloria Carmona y Pere Plans, de la Agencia de Salud P\u00fablica de Catalu\u00f1a del Departamento de Salud. <\/p>\n<p class=\"MsoNormal\">A lo largo de las 4h que dur\u00f3 el curso,<b> <\/b>se profundiz\u00f3 en aspectos como el <b>funcionamiento general de la red y c\u00f3mo realizar el registro de datos obtenidos.<\/b> Y, m\u00e1s concretamente, entre otros temas, se abord\u00f3<b> c\u00f3mo hacer el seguimiento de las alertas de calidad de medicamentos, c\u00f3mo notificar la sospecha de errores de medicaci\u00f3n o reacciones adversas a medicamentos<\/b>, y tambi\u00e9n <b>qu\u00e9 debe tenerse en cuenta para identificar posibles casos de uso de medicamentos con finalidad no terap\u00e9utica. \u00a0<\/b><\/p>\n<p class=\"MsoNormal\"><b><\/p>\n<p><u>\u00bfEn qu\u00e9 campos act\u00faan las farmacias centinelas?<\/u> <\/p>\n<p><\/b><\/p>\n<p>Las dos grandes \u00e1reas en las que han actuado los farmac\u00e9uticos durante la fase piloto han sido, por un lado, la <strong>farmacovigilancia,<\/strong> centrada en la detecci\u00f3n, evaluaci\u00f3n, conocimiento y prevenci\u00f3n de los efectos adversos de los medicamentos. Dentro de este campo, <strong>los farmac\u00e9uticos tienen como funciones principales seguir las alertas farmac\u00e9uticas de desabastecimiento de medicamento<\/strong>s -registrando, por ejemplo, el n\u00famero de pacientes que han pedido el medicamento afectado-, <strong>as\u00ed como las alertas de calidad<\/strong> -para garantizar, entre otros, la correcta retirada de los medicamentos en los que se han podido detectar defectos-. Al mismo tiempo, <strong>son los encargados de notificar una sospecha de reacci\u00f3n adversa a un f\u00e1rmaco, vigilar los medicamentos sujetos a seguimiento adicional <\/strong>-aquellos sobre los que se dispone de menos informaci\u00f3n, porque se ha comercializado recientemente o porque la informaci\u00f3n que se tiene sobre su uso a largo plazo es limitada-.<\/p>\n<p>Por otra parte,<strong> detectar y registrar la sospecha de abuso o uso desviado de medicamentos con una finalidad no terap\u00e9utica. <\/strong>Con esta acci\u00f3n, contribuyen a apoyar al Observatorio de Medicamentos de Abuso (OMA) en su labor como \u00f3rgano de vigilancia epidemiol\u00f3gica y tambi\u00e9n en su estudio del consumo a nivel poblacional.<\/p>\n<p class=\"Default\"><strong>Para m\u00e1s informaci\u00f3n: <\/strong><br \/>Prensa Salud: premsa@gencat.cat<\/p>\n<p>Departamento de Comunicaci\u00f3n del Consejo de Colegios Farmac\u00e9uticos de Catalu\u00f1a <br \/>Tel\u00e9fono: 93 244 07 28\/18 \u2013 premsa@cofb.net  <br \/>\u00a0<\/p>\n<p>\u00a0La formaci\u00f3n tuvo lugar la semana pasada en el Colegio de Farmac\u00e9uticos de Barcelona, con conexi\u00f3n para webinar en las sedes de los COFs de Girona, Lleida y TarragonaDespu\u00e9s del \u00e9xito de la prueba piloto en Barcelona, est\u00e1 previsto que en el 1 de julio se inicie la puesta en marcha de la Red Centinela en toda CatalunyaForma parte de la estrategia de despliegue del Plan de Salud 2016-2020 Barcelona, 19 de junio de 2017. Farmac\u00e9uticos catalanes se formaron la semana pasada para participar en la red de farmacias centinelas. Superada la formaci\u00f3n, y tras el \u00e9xito de la prueba piloto llevada a cabo en Barcelona, est\u00e1 previsto que el proyecto se inicie el d\u00eda 1 de julio en el resto de Catalu\u00f1a.  En el marco de esta iniciativa, impulsada por el Departamento de Salud de la Generalitat y el Consejo de Colegios Farmac\u00e9uticos de Catalu\u00f1a, las farmacias trabajan conjuntamente para aportar informaci\u00f3n sobre incidentes de seguridad relacionados con el uso de los medicamentos -como el seguimiento espec\u00edfico de determinados medicamentos-, para monitorizar su abuso o uso recreativo y para obtener datos que se puedan integrar en sistemas de vigilancia de otros profesionales sanitarios. Esta informaci\u00f3n de primera mano ayuda a planificar actuaciones espec\u00edficas de mejora en el uso de los medicamentos en Catalu\u00f1a, a trav\u00e9s de estrategias de actuaci\u00f3n coordinadas entre las instituciones sanitarias y colegiales. Asimismo, la constituci\u00f3n de esta red estable de farmacias centinelas permite obtener datos v\u00e1lidos generados por la propia din\u00e1mica asistencial y que pueden integrarse en el sistema de vigilancia epidemiol\u00f3gica, facilitando una respuesta m\u00e1s eficaz de los servicios de salud p\u00fablica. \u00bfEn qu\u00e9 consisti\u00f3 la formaci\u00f3n? Durante la tarde del mi\u00e9rcoles 14 de junio tuvo lugar en el Colegio de Farmac\u00e9uticos de Barcelona, con conexi\u00f3n para webinar en las sedes de los COFs de Girona, Lleida y Tarragona, una formaci\u00f3n espec\u00edfica en la que se van dar las herramientas necesarias a los farmac\u00e9uticos para que puedan formar parte de la Red. Esta formaci\u00f3n corri\u00f3 a cargo de Pilar Gasc\u00f3n, secretaria del Consejo de Colegios Farmac\u00e9uticos de Catalunya (CCFC); Ma Jos\u00e9 Gaspar, jefe de Servicio de Ordenaci\u00f3n y Calidad Farmac\u00e9utica; Manel Rabanal, jefe de Secci\u00f3n de Vigilancia y Publicidad del Medicamento;  Anna Maria Jambrina, de la Direcci\u00f3n General de Ordenaci\u00f3n Profesional y Regulaci\u00f3n Sanitaria del Departament de Salut; Gloria Cereza, del Centro Auton\u00f3mico de Farmacovigilancia de Catalu\u00f1a; Rafael Guayta-Escolies, director de Proyectos e Investigaci\u00f3n del CCFC; Maria Perell\u00f3, del Centro de Informaci\u00f3n del Medicamento del COFB; Pilar Rius, del Consejo de Colegios de Farmac\u00e9uticos de Catalu\u00f1a; y Gloria Carmona y Pere Plans, de la Agencia de Salud P\u00fablica de Catalu\u00f1a del Departamento de Salud. A lo largo de las 4h que dur\u00f3 el curso, se profundiz\u00f3 en aspectos como el funcionamiento general de la red y c\u00f3mo realizar el registro de datos obtenidos. Y, m\u00e1s concretamente, entre otros temas, se abord\u00f3 c\u00f3mo realizar el seguimiento de las alertas de calidad de medicamentos, c\u00f3mo notificar la sospecha de errores de medicaci\u00f3n o reacciones adversas a medicamentos, y tambi\u00e9n qu\u00e9 debe tenerse en cuenta para identificar posibles casos de uso de medicamentos con fines no terap\u00e9uticos.  \u00bfEn qu\u00e9 campos act\u00faan las farmacias centinelas? Las dos grandes \u00e1reas en las que han actuado los farmac\u00e9uticos durante la fase piloto han sido, por un lado, la farmacovigilancia, centrada en la detecci\u00f3n, evaluaci\u00f3n, conocimiento y prevenci\u00f3n de los efectos adversos de los medicamentos. Dentro de este campo, los farmac\u00e9uticos tienen como principales funciones seguir las alertas farmac\u00e9uticas de desabastecimiento de medicamentos -registrando, por ejemplo, el n\u00famero de pacientes que han pedido el medicamento afectado-, as\u00ed como las alertas de calidad -para garantizar, entre otros, la correcta retirada de los medicamentos en los que se han podido detectar defectos-. Asimismo, son los encargados de notificar una sospecha de reacci\u00f3n adversa a un f\u00e1rmaco, vigilar los medicamentos sujetos a seguimiento adicional -aquellos sobre los que se dispone de menos informaci\u00f3n, porque se ha comercializado recientemente o porque la informaci\u00f3n que se tiene sobre el suyo uso a largo plazo es limitada-.Por otra parte, detectar y registrar la sospecha de abuso o uso desviado de medicamentos con una finalidad no terap\u00e9utica. Con esta acci\u00f3n, contribuyen a apoyar al Observatorio de Medicamentos de Abuso (OMA) en su labor como \u00f3rgano de vigilancia epidemiol\u00f3gica y tambi\u00e9n en su estudio del consumo a nivel poblacional. Para m\u00e1s informaci\u00f3n: Prensa Salud premsa@gencat.catDepartamento de Comunicaci\u00f3n del Consejo de Colegios Farmac\u00e9uticos de Catalu\u00f1a Tel\u00e9fono: 93 244 07 28 \/ 18 \u2013 premsa@cofb.net COFB.ORG<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 La formaci\u00f3n tuvo lugar la semana pasada en el Colegio de Farmac\u00e9uticos de Barcelona, con conexi\u00f3n para webinar en las sedes de los COFs de Girona, Lleida y Tarragona.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1060,1066],"tags":[],"class_list":["post-77308","post","type-post","status-publish","format-standard","hentry","category-notes-premsa","category-sense-categoria-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Farmac\u00e8utics catalans es formen per participar a la xarxa de farm\u00e0cies sentinelles - Col\u00b7legi de Farmac\u00e8utics de Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Farmac\u00e8utics catalans es formen per participar a la xarxa de farm\u00e0cies sentinelles - Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"og:description\" content=\"\u00a0 La formaci\u00f3 va tenir lloc la setmana passada al Col\u00b7legi de Farmac\u00e8utics de Barcelona, amb connexi\u00f3 per webinar a les seus dels COFs de Girona, Lleida i Tarragona Despr\u00e9s de l\u2019\u00e8xit de la prova pilot a Barcelona, est\u00e0 previst que a l\u20191 de juliol s\u2019inici\u00ef la posta en marxa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-19T12:52:00+00:00\" \/>\n<meta name=\"author\" content=\"wpAdminCofbOrg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:site\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpAdminCofbOrg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/\"},\"author\":{\"name\":\"wpAdminCofbOrg\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\"},\"headline\":\"Farmac\u00e8utics catalans es formen per participar a la xarxa de farm\u00e0cies sentinelles\",\"datePublished\":\"2017-06-19T12:52:00+00:00\",\"dateModified\":\"2017-06-19T12:52:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/\"},\"wordCount\":1647,\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"articleSection\":[\"Notes de premsa\",\"Sense categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/\",\"url\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/\",\"name\":\"Farmac\u00e8utics catalans es formen per participar a la xarxa de farm\u00e0cies sentinelles - Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.cofb.org\/#website\"},\"datePublished\":\"2017-06-19T12:52:00+00:00\",\"dateModified\":\"2017-06-19T12:52:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.cofb.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Farmac\u00e8utics catalans es formen per participar a la xarxa de farm\u00e0cies sentinelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cofb.org\/#website\",\"url\":\"https:\/\/www.cofb.org\/\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cofb.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cofb.org\/#organization\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"url\":\"https:\/\/www.cofb.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"contentUrl\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"width\":500,\"height\":105,\"caption\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\"},\"image\":{\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\",\"https:\/\/twitter.com\/farmaceuticsbcn\",\"https:\/\/www.instagram.com\/farmaceuticsbcn\/\",\"https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\",\"name\":\"wpAdminCofbOrg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"caption\":\"wpAdminCofbOrg\"},\"sameAs\":[\"http:\/\/192.168.64.122\/wordpress\"],\"url\":\"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Farmac\u00e8utics catalans es formen per participar a la xarxa de farm\u00e0cies sentinelles - Col\u00b7legi de Farmac\u00e8utics de Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/","og_locale":"es_ES","og_type":"article","og_title":"Farmac\u00e8utics catalans es formen per participar a la xarxa de farm\u00e0cies sentinelles - Col\u00b7legi de Farmac\u00e8utics de Barcelona","og_description":"\u00a0 La formaci\u00f3 va tenir lloc la setmana passada al Col\u00b7legi de Farmac\u00e8utics de Barcelona, amb connexi\u00f3 per webinar a les seus dels COFs de Girona, Lleida i Tarragona Despr\u00e9s de l\u2019\u00e8xit de la prova pilot a Barcelona, est\u00e0 previst que a l\u20191 de juliol s\u2019inici\u00ef la posta en marxa [&hellip;]","og_url":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/","og_site_name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","article_publisher":"https:\/\/www.facebook.com\/farmaceuticsbcn\/","article_published_time":"2017-06-19T12:52:00+00:00","author":"wpAdminCofbOrg","twitter_card":"summary_large_image","twitter_creator":"@farmaceuticsbcn","twitter_site":"@farmaceuticsbcn","twitter_misc":{"Escrito por":"wpAdminCofbOrg","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/#article","isPartOf":{"@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/"},"author":{"name":"wpAdminCofbOrg","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb"},"headline":"Farmac\u00e8utics catalans es formen per participar a la xarxa de farm\u00e0cies sentinelles","datePublished":"2017-06-19T12:52:00+00:00","dateModified":"2017-06-19T12:52:00+00:00","mainEntityOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/"},"wordCount":1647,"publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"articleSection":["Notes de premsa","Sense categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/","url":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/","name":"Farmac\u00e8utics catalans es formen per participar a la xarxa de farm\u00e0cies sentinelles - Col\u00b7legi de Farmac\u00e8utics de Barcelona","isPartOf":{"@id":"https:\/\/www.cofb.org\/#website"},"datePublished":"2017-06-19T12:52:00+00:00","dateModified":"2017-06-19T12:52:00+00:00","breadcrumb":{"@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/farmaceutics-catalans-es-formen-per-participar-a-la-xarxa-de-farmacies-sentinelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cofb.org\/"},{"@type":"ListItem","position":2,"name":"Farmac\u00e8utics catalans es formen per participar a la xarxa de farm\u00e0cies sentinelles"}]},{"@type":"WebSite","@id":"https:\/\/www.cofb.org\/#website","url":"https:\/\/www.cofb.org\/","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","description":"","publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cofb.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cofb.org\/#organization","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","url":"https:\/\/www.cofb.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","contentUrl":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","width":500,"height":105,"caption":"Col\u00b7legi de Farmac\u00e8utics de Barcelona"},"image":{"@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/farmaceuticsbcn\/","https:\/\/twitter.com\/farmaceuticsbcn","https:\/\/www.instagram.com\/farmaceuticsbcn\/","https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/"]},{"@type":"Person","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb","name":"wpAdminCofbOrg","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","caption":"wpAdminCofbOrg"},"sameAs":["http:\/\/192.168.64.122\/wordpress"],"url":"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"wpAdminCofbOrg","author_link":"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00a0 La formaci\u00f3 va tenir lloc la setmana passada al Col\u00b7legi de Farmac\u00e8utics de Barcelona, amb connexi\u00f3 per webinar a les seus dels COFs de Girona, Lleida i Tarragona Despr\u00e9s de l\u2019\u00e8xit de la prova pilot a Barcelona, est\u00e0 previst que a l\u20191 de juliol s\u2019inici\u00ef la posta en marxa [&hellip;]","_links":{"self":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts\/77308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/comments?post=77308"}],"version-history":[{"count":0,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts\/77308\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/media?parent=77308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/categories?post=77308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/tags?post=77308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}