{"id":52058,"date":"2020-10-26T15:45:11","date_gmt":"2020-10-26T13:45:11","guid":{"rendered":"https:\/\/blog.cofb.cat\/?p=52058"},"modified":"2020-10-26T15:45:11","modified_gmt":"2020-10-26T13:45:11","slug":"resolucio-convocatoria-2020-2021-beques-premis-cofb","status":"publish","type":"post","link":"https:\/\/www.cofb.org\/es\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/","title":{"rendered":"Resoluci\u00f3n de la convocatoria 2020-2021 de becas y premios del COFB"},"content":{"rendered":"<p>En la sesi\u00f3n del d\u00eda <strong>17 de septiembre<\/strong>, la <strong>Junta de Gobierno del Colegio de Farmac\u00e9uticos de Barcelona (COFB) <\/strong>aprob\u00f3 el acuerdo del tribunal de becas y premios que resuelve la convocatoria 2020-21.<\/p>\n<p>\u00c9sta <strong>convocatoria<\/strong> ha incluido la <strong>beca de investigaci\u00f3n<\/strong>, el <strong>premio al mejor art\u00edculo publicado en la revista Circular Farmac\u00e9utica<\/strong> durante el 2019 y el <strong>premio al mejor trabajo de fin de grado<\/strong> 2019.<\/p>\n<figure id=\"attachment_52414\" aria-describedby=\"caption-attachment-52414\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.cofb.cat\/wp-content\/uploads\/2020\/10\/cofb.201008-08.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-52414 size-large\" title=\"Miembros de la Comisi\u00f3n de Becas del COFB con Jordi Casas, presidente del Colegio, y autores de los trabajos becados\/premiados.\" src=\"https:\/\/blog.cofb.cat\/wp-content\/uploads\/2020\/10\/cofb.201008-08-1024x683.jpg\" alt=\"Membres de la Comissi\u00f3 de Beques del COFB amb Jordi Casas, president del Col\u00b7legi, i autors dels treballs becats\/premiats.\" width=\"620\" height=\"414\" \/><\/a><figcaption id=\"caption-attachment-52414\" class=\"wp-caption-text\">Miembros de la Comisi\u00f3n de Becas del COFB con Jordi Casas, presidente del Colegio, y autores de los trabajos becados\/premiados.<\/figcaption><\/figure>\n<p>Las <strong>bases de la convocatoria<\/strong> especifican los aspectos a evaluar relativos a <strong>el equipo investigador<\/strong>, al <strong>proyecto<\/strong> en s\u00ed ya <strong>el inter\u00e9s <\/strong>para el colectivo farmac\u00e9utico.<\/p>\n<h1><strong>Resoluci\u00f3n de la convocatoria 2020-2021 de becas y premios del COFB<\/strong><\/h1>\n<h2><strong>Beca de investigaci\u00f3n<\/strong><\/h2>\n<p>Dotada con <strong>9.000 \u20ac<\/strong> por la becada, ha sido <strong>otorgada al siguiente proyecto<\/strong>:<\/p>\n<ul>\n<li><strong>B\u00fasqueda de marcadores s\u00e9ricos pron\u00f3sticos precoces de disfunci\u00f3n\/quiebra org\u00e1nica en pacientes hospitalizados por COVID mediante metabol\u00f3mica High-Throughput<\/strong>. Investigadores: M\u00aa Carmen Salgado Mart\u00edn, Jos\u00e9 Alcaraz Quiles. Hospital Cl\u00ednico de Barcelona.<\/li>\n<\/ul>\n<figure id=\"attachment_52402\" aria-describedby=\"caption-attachment-52402\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.cofb.cat\/wp-content\/uploads\/2020\/10\/M-Carmen-Salgado.jpg\"><img decoding=\"async\" class=\"wp-image-52402 size-large\" title=\"En primer plano, M\u00aa Carmen Salgado, acompa\u00f1ada de miembros de la Comisi\u00f3n de Becas y Premios del Colegio. \" src=\"https:\/\/blog.cofb.cat\/wp-content\/uploads\/2020\/10\/M-Carmen-Salgado-1024x683.jpg\" alt=\"En primer pla, M\u00aa Carmen Salgado, acompanyada de membres de la Comissi\u00f3 de Beques i Premis del Col\u00b7legi. \" width=\"620\" height=\"414\" \/><\/a><figcaption id=\"caption-attachment-52402\" class=\"wp-caption-text\">En primer plano, M\u00aa Carmen Salgado, acompa\u00f1ada de miembros de la Comisi\u00f3n de Becas y Premios del Colegio.<\/figcaption><\/figure>\n<h2><strong>Premio al mejor art\u00edculo publicado en la Circular Farmac\u00e9utica<\/strong><\/h2>\n<p>Dotado con <strong>1.000 \u20ac<\/strong>, el <strong>premiado<\/strong> fue el siguiente <strong>art\u00edculo<\/strong>:<\/p>\n<ul>\n<li><strong>La gripe espa\u00f1ola en Catalu\u00f1a, un punto de inflexi\u00f3n en la profesi\u00f3n farmac\u00e9utica. <\/strong>Autor: Fernando Parrilla Valero.<\/li>\n<\/ul>\n<figure id=\"attachment_52401\" aria-describedby=\"caption-attachment-52401\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.cofb.cat\/wp-content\/uploads\/2020\/10\/Fernando-Parrilla.jpg\"><img decoding=\"async\" class=\"wp-image-52401 size-large\" title=\"En primer plano, Fernando Parrilla, acompa\u00f1ado de miembros de la Comisi\u00f3n de Becas y Premios del COFB.\" src=\"https:\/\/blog.cofb.cat\/wp-content\/uploads\/2020\/10\/Fernando-Parrilla-1024x683.jpg\" alt=\"En primer pla, Fernando Parrilla, acompanyat de membres de la Comissi\u00f3 de Beques i Premis del COFB.\" width=\"620\" height=\"414\" \/><\/a><figcaption id=\"caption-attachment-52401\" class=\"wp-caption-text\">En primer plano, Fernando Parrilla, acompa\u00f1ado de miembros de la Comisi\u00f3n de Becas y Premios del COFB.<\/figcaption><\/figure>\n<h2><strong>Premio al mejor trabajo de fin de grado (TFG) presentado en 2019<\/strong><\/h2>\n<p>Los <strong>ganadores a mejores TFG<\/strong> presentados en 2019 fueron premiados con <strong>500 \u20ac cada uno<\/strong>:<\/p>\n<ul>\n<li><strong>Estudio del papel de la prote\u00edna Gq en la mitofagia<\/strong>. Autora: Alicia Josa Culler\u00e9. Tutores: Anna Maria Aragay Combas y Juan Carlos Rodr\u00edguez. Departamento de Bioqu\u00edmica y Fisiopatolog\u00eda de la Facultad de Farmacia y Ciencias de la Alimentaci\u00f3n de la Universidad de Barcelona, y el Instituto de Biolog\u00eda Molecular de Barcelona (CSIC).<\/li>\n<\/ul>\n<figure id=\"attachment_52405\" aria-describedby=\"caption-attachment-52405\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.cofb.cat\/wp-content\/uploads\/2020\/10\/Alicia-Josa-Culler\u00e9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-52405 size-large\" title=\"En primer plano, Alicia Josa, acompa\u00f1ada de miembros de la Comisi\u00f3n de Becas y Premios del COFB.\" src=\"https:\/\/blog.cofb.cat\/wp-content\/uploads\/2020\/10\/Alicia-Josa-Culler\u00e9-1024x683.jpg\" alt=\"En primer pla, Alicia Josa, acompanyada de membres de la Comissi\u00f3 de Beques i Premis del COFB.\" width=\"620\" height=\"414\" \/><\/a><figcaption id=\"caption-attachment-52405\" class=\"wp-caption-text\">En primer plano, Alicia Josa, acompa\u00f1ada de miembros de la Comisi\u00f3n de Becas y Premios del COFB.<\/figcaption><\/figure>\n<ul>\n<li><strong>S\u00edntesis de una familia de catinones potencialmente activas. <\/strong>Autora: N\u00faria Nadal Gratac\u00f3s. Tutor: Xavier Berzosa Rodr\u00edguez. Departamento de Qu\u00edmica Farmac\u00e9utica. Grado en Farmacia del Instituto Qu\u00edmico de Sarri\u00e0 - Blanquerna FCS (Universidad Ramon Llull).<\/li>\n<\/ul>\n<figure id=\"attachment_52404\" aria-describedby=\"caption-attachment-52404\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blog.cofb.cat\/wp-content\/uploads\/2020\/10\/N\u00faria-Nadal-Gratac\u00f3s.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-52404 size-large\" title=\"En primer plano, N\u00faria Nadal, acompa\u00f1ada de miembros de la Comisi\u00f3n de Becas y Premios del COFB. \" src=\"https:\/\/blog.cofb.cat\/wp-content\/uploads\/2020\/10\/N\u00faria-Nadal-Gratac\u00f3s-1024x683.jpg\" alt=\"En primer pla, N\u00faria Nadal, acompanyada de membres de la Comissi\u00f3 de Beques i Premis del COFB. \" width=\"620\" height=\"414\" \/><\/a><figcaption id=\"caption-attachment-52404\" class=\"wp-caption-text\">En primer plano, N\u00faria Nadal, acompa\u00f1ada de miembros de la Comisi\u00f3n de Becas y Premios del COFB.<\/figcaption><\/figure>\n<ul>\n<li><strong>Optimizaci\u00f3n de la resistencia a antiinfecciosos en la pr\u00e1ctica cl\u00ednica: <\/strong>Autora: Maria Bascones Roig. Tutores: Concepci\u00f3n Maestros Miralles y Marta Hern\u00e1ndez Hern\u00e1ndez. Grado en Farmacia del Instituto Qu\u00edmico de Sarri\u00e0 - Blanquerna FCS (Universidad Ramon Llull).<\/li>\n<li><strong>El eje microbiota-intestino-cerebro y su relaci\u00f3n con la depresi\u00f3n<\/strong>. Autora: Irene Balasch Esteve. Tutora: Raquel Martin Venegas. Departamento de Bioqu\u00edmica y Fisiopatolog\u00eda de la Facultad de Farmacia y Ciencias de la Alimentaci\u00f3n de la Universidad de Barcelona.<\/li>\n<\/ul>\n<div class=\"destacat-blog\">\n<h2><strong>Los miembros del Tribunal<\/strong><\/h2>\n<p>El <strong>Tribunal<\/strong> que ha evaluado las solicitudes recibidas para optar a beca o premio, y que seguir\u00e1 el desarrollo del trabajo becado, est\u00e1 formado por los farmac\u00e9uticos: <strong>Guillermo Bagaria<\/strong>, <strong>M\u00aa Rosa Ballester<\/strong>, <strong>Merc\u00e8 Barau<\/strong>, <strong>David Conde<\/strong>, <strong>Pilar Gasc\u00f3n<\/strong>, <strong>Josep Manel Llop<\/strong>, <strong>Cristina Roure<\/strong>, <strong>Xavier Tejedor<\/strong>, <strong>Roser Vall\u00e9s<\/strong>, <strong>Angelina Baena<\/strong>, <strong>Marta Hern\u00e1ndez<\/strong> y <strong>Josefina Tapias<\/strong>.<\/p>\n<\/div>\n<p><strong>Otras publicaciones de inter\u00e9s:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/blog.cofb.cat\/circular-farmaceutica-ja-disponible-ledicio-especial-de-premis-i-beques\/\" target=\"_blank\" rel=\"noopener\">Circular Farmac\u00e9utica: Ya disponible la edici\u00f3n especial de premios y becas (Abril 2020)<\/a><\/li>\n<li><a href=\"https:\/\/blog.cofb.cat\/oberta-la-convocatoria-de-beques-i-premis-2019-del-collegi-de-farmaceutics-de-barcelona\/\" target=\"_blank\" rel=\"noopener\">Abierta la convocatoria de becas y premios 2019 del Colegio de Farmac\u00e9uticos de Barcelona (Mayo 2019)<\/a><\/li>\n<li><a href=\"https:\/\/blog.cofb.cat\/presentacio-dels-resultats-finals-dels-treballs-becats-en-la-convocatoria-2017-18\/\" target=\"_blank\" rel=\"noopener\">Presentaci\u00f3n de los resultados finales de los trabajos becados en la convocatoria 2017-18 (Noviembre 2018)<\/a><\/li>\n<li><a href=\"https:\/\/blog.cofb.cat\/beques-collegials-cofb-projectes-becats-convocatoria-2018-2019\/\" target=\"_blank\" rel=\"noopener\">Becas colegiales del COFB: proyectos becados en la convocatoria 2018-2019 (Julio 2018)<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>En la sesi\u00f3n del 17 de septiembre, la Junta de Gobierno del Colegio de Farmac\u00e9uticos de Barcelona (COFB) aprob\u00f3 el acuerdo del tribunal de becas y premios que resuelve la convocatoria 2020-21. Esta convocatoria ha incluido la beca de investigaci\u00f3n, el premio al mejor art\u00edculo publicado en la revista Circular [\u2026]<\/p>","protected":false},"author":1,"featured_media":52414,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[23,57],"tags":[4326,48,355,89,494,3430,401,470,4327,3761,4328,4329,4330,417,4331,4332,4333,4334,2418,358,4335,906,62,4336,2549,4337,3038,3502,4338],"class_list":["post-52058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacats","category-mon-collegial","tag-angelina-baena","tag-beca-dinvestigacio","tag-beques-i-premis","tag-circular-farmaceutica","tag-covid","tag-cristina-roure","tag-david-conde","tag-depressio","tag-grip-espanyola","tag-guillermo-bagaria","tag-institut-de-biologia-molecular-de-barcelona","tag-josefina-tapias","tag-josep-manel-llop","tag-junta-de-govern","tag-ma-rosa-ballester","tag-marta-hernandez","tag-merce-barau","tag-mitofagia","tag-pilar-gascon","tag-premi-a-millor-article-publicat-a-circular-farmaceutica","tag-premi-a-millor-treball-de-fi-de-grau","tag-professio-farmaceutica","tag-projectes-becats","tag-resistencia-a-antiinfecciosos","tag-roser-valles","tag-treball-de-fi-de-grau","tag-universitat-de-barcelona","tag-universitat-ramon-llull","tag-xavier-tejedor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Resoluci\u00f3 de la convocat\u00f2ria 2020-2021 de beques i premis del COFB - Col\u00b7legi de Farmac\u00e8utics de Barcelona<\/title>\n<meta name=\"description\" content=\"En la sessi\u00f3 del dia 17 de setembre, la Junta de Govern del Col\u00b7legi de Farmac\u00e8utics de Barcelona va aprovar l\u2019acord del tribunal de beques i premis que resol la convocat\u00f2ria 2020-21.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resoluci\u00f3 de la convocat\u00f2ria 2020-2021 de beques i premis del COFB - Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"og:description\" content=\"En la sessi\u00f3 del dia 17 de setembre, la Junta de Govern del Col\u00b7legi de Farmac\u00e8utics de Barcelona va aprovar l\u2019acord del tribunal de beques i premis que resol la convocat\u00f2ria 2020-21.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-26T13:45:11+00:00\" \/>\n<meta name=\"author\" content=\"wpAdminCofbOrg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:site\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpAdminCofbOrg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/\"},\"author\":{\"name\":\"wpAdminCofbOrg\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\"},\"headline\":\"Resoluci\u00f3 de la convocat\u00f2ria 2020-2021 de beques i premis del COFB\",\"datePublished\":\"2020-10-26T13:45:11+00:00\",\"dateModified\":\"2020-10-26T13:45:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/\"},\"wordCount\":680,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Angelina Baena\",\"beca d'investigaci\u00f3\",\"beques i premis\",\"Circular Farmac\u00e8utica\",\"covid\",\"Cristina Roure\",\"David Conde\",\"depressi\u00f3\",\"grip espanyola\",\"Guillermo Bagaria\",\"Institut de Biologia Molecular de Barcelona\",\"Josefina Tapias\",\"Josep Manel Llop\",\"Junta de Govern\",\"M\u00aa Rosa Ballester\",\"Marta Hern\u00e1ndez\",\"Merc\u00e8 Barau\",\"mitof\u00e0gia\",\"Pilar Gasc\u00f3n\",\"premi a millor article publicat a Circular Farmac\u00e8utica\",\"premi a millor treball de fi de grau\",\"professi\u00f3 farmac\u00e8utica\",\"projectes becats\",\"resist\u00e8ncia a antiinfecciosos\",\"Roser Vall\u00e8s\",\"Treball de fi de grau\",\"Universitat de Barcelona\",\"Universitat Ramon Llull\",\"Xavier Tejedor\"],\"articleSection\":[\"Destacats\",\"M\u00f3n col\u00b7legial\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/\",\"url\":\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/\",\"name\":\"Resoluci\u00f3 de la convocat\u00f2ria 2020-2021 de beques i premis del COFB - Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.cofb.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-10-26T13:45:11+00:00\",\"dateModified\":\"2020-10-26T13:45:11+00:00\",\"description\":\"En la sessi\u00f3 del dia 17 de setembre, la Junta de Govern del Col\u00b7legi de Farmac\u00e8utics de Barcelona va aprovar l\u2019acord del tribunal de beques i premis que resol la convocat\u00f2ria 2020-21.\",\"breadcrumb\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/novaorg.cofb.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resoluci\u00f3 de la convocat\u00f2ria 2020-2021 de beques i premis del COFB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cofb.org\/#website\",\"url\":\"https:\/\/www.cofb.org\/\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cofb.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cofb.org\/#organization\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"url\":\"https:\/\/www.cofb.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"contentUrl\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"width\":500,\"height\":105,\"caption\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\"},\"image\":{\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\",\"https:\/\/twitter.com\/farmaceuticsbcn\",\"https:\/\/www.instagram.com\/farmaceuticsbcn\/\",\"https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\",\"name\":\"wpAdminCofbOrg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"caption\":\"wpAdminCofbOrg\"},\"sameAs\":[\"http:\/\/192.168.64.122\/wordpress\"],\"url\":\"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resoluci\u00f3 de la convocat\u00f2ria 2020-2021 de beques i premis del COFB - Col\u00b7legi de Farmac\u00e8utics de Barcelona","description":"En la sessi\u00f3 del dia 17 de setembre, la Junta de Govern del Col\u00b7legi de Farmac\u00e8utics de Barcelona va aprovar l\u2019acord del tribunal de beques i premis que resol la convocat\u00f2ria 2020-21.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/","og_locale":"es_ES","og_type":"article","og_title":"Resoluci\u00f3 de la convocat\u00f2ria 2020-2021 de beques i premis del COFB - Col\u00b7legi de Farmac\u00e8utics de Barcelona","og_description":"En la sessi\u00f3 del dia 17 de setembre, la Junta de Govern del Col\u00b7legi de Farmac\u00e8utics de Barcelona va aprovar l\u2019acord del tribunal de beques i premis que resol la convocat\u00f2ria 2020-21.","og_url":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/","og_site_name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","article_publisher":"https:\/\/www.facebook.com\/farmaceuticsbcn\/","article_published_time":"2020-10-26T13:45:11+00:00","author":"wpAdminCofbOrg","twitter_card":"summary_large_image","twitter_creator":"@farmaceuticsbcn","twitter_site":"@farmaceuticsbcn","twitter_misc":{"Escrito por":"wpAdminCofbOrg","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#article","isPartOf":{"@id":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/"},"author":{"name":"wpAdminCofbOrg","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb"},"headline":"Resoluci\u00f3 de la convocat\u00f2ria 2020-2021 de beques i premis del COFB","datePublished":"2020-10-26T13:45:11+00:00","dateModified":"2020-10-26T13:45:11+00:00","mainEntityOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/"},"wordCount":680,"commentCount":0,"publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"image":{"@id":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#primaryimage"},"thumbnailUrl":"","keywords":["Angelina Baena","beca d'investigaci\u00f3","beques i premis","Circular Farmac\u00e8utica","covid","Cristina Roure","David Conde","depressi\u00f3","grip espanyola","Guillermo Bagaria","Institut de Biologia Molecular de Barcelona","Josefina Tapias","Josep Manel Llop","Junta de Govern","M\u00aa Rosa Ballester","Marta Hern\u00e1ndez","Merc\u00e8 Barau","mitof\u00e0gia","Pilar Gasc\u00f3n","premi a millor article publicat a Circular Farmac\u00e8utica","premi a millor treball de fi de grau","professi\u00f3 farmac\u00e8utica","projectes becats","resist\u00e8ncia a antiinfecciosos","Roser Vall\u00e8s","Treball de fi de grau","Universitat de Barcelona","Universitat Ramon Llull","Xavier Tejedor"],"articleSection":["Destacats","M\u00f3n col\u00b7legial"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/","url":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/","name":"Resoluci\u00f3 de la convocat\u00f2ria 2020-2021 de beques i premis del COFB - Col\u00b7legi de Farmac\u00e8utics de Barcelona","isPartOf":{"@id":"https:\/\/www.cofb.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#primaryimage"},"image":{"@id":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-10-26T13:45:11+00:00","dateModified":"2020-10-26T13:45:11+00:00","description":"En la sessi\u00f3 del dia 17 de setembre, la Junta de Govern del Col\u00b7legi de Farmac\u00e8utics de Barcelona va aprovar l\u2019acord del tribunal de beques i premis que resol la convocat\u00f2ria 2020-21.","breadcrumb":{"@id":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/novaorg.cofb.net\/2020\/10\/26\/resolucio-convocatoria-2020-2021-beques-premis-cofb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/novaorg.cofb.net\/"},{"@type":"ListItem","position":2,"name":"Resoluci\u00f3 de la convocat\u00f2ria 2020-2021 de beques i premis del COFB"}]},{"@type":"WebSite","@id":"https:\/\/www.cofb.org\/#website","url":"https:\/\/www.cofb.org\/","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","description":"","publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cofb.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cofb.org\/#organization","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","url":"https:\/\/www.cofb.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","contentUrl":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","width":500,"height":105,"caption":"Col\u00b7legi de Farmac\u00e8utics de Barcelona"},"image":{"@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/farmaceuticsbcn\/","https:\/\/twitter.com\/farmaceuticsbcn","https:\/\/www.instagram.com\/farmaceuticsbcn\/","https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/"]},{"@type":"Person","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb","name":"wpAdminCofbOrg","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","caption":"wpAdminCofbOrg"},"sameAs":["http:\/\/192.168.64.122\/wordpress"],"url":"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"wpAdminCofbOrg","author_link":"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/"},"uagb_comment_info":0,"uagb_excerpt":"En la sessi\u00f3 del dia 17 de setembre, la Junta de Govern del Col\u00b7legi de Farmac\u00e8utics de Barcelona (COFB) va aprovar l\u2019acord del tribunal de beques i premis que resol la convocat\u00f2ria 2020-21. Aquesta convocat\u00f2ria ha incl\u00f2s la beca d\u2019investigaci\u00f3, el premi al millor article publicat a la revista Circular [&hellip;]","_links":{"self":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts\/52058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/comments?post=52058"}],"version-history":[{"count":0,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts\/52058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/media?parent=52058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/categories?post=52058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/tags?post=52058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}