{"id":30942,"date":"2017-06-19T13:39:20","date_gmt":"2017-06-19T12:39:20","guid":{"rendered":"http:\/\/blog.cofb.cat\/?p=30942"},"modified":"2017-06-19T13:39:20","modified_gmt":"2017-06-19T12:39:20","slug":"junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016","status":"publish","type":"post","link":"https:\/\/www.cofb.org\/es\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/","title":{"rendered":"Junta General Ordinaria: los colegiados aprueban la liquidaci\u00f3n del presupuesto 2016"},"content":{"rendered":"<p>El equipo econ\u00f3mico de la Junta de Gobierno del Colegio present\u00f3 a la Junta General Ordinaria celebrada ayer, 15 de junio, la <b>liquidaci\u00f3n del presupuesto del ejercicio 2016<\/b>, recibiendo la aprobaci\u00f3n por unanimidad de los colegiados asistentes.<\/p>\n<figure id=\"attachment_30984\" aria-describedby=\"caption-attachment-30984\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/blog.cofb.cat\/wp-content\/uploads\/2017\/06\/JGO-COFB-juny-2.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-30984\" title=\"Junta General Ordinaria: los colegiados aprueban la liquidaci\u00f3n del presupuesto 2016\" src=\"http:\/\/blog.cofb.cat\/wp-content\/uploads\/2017\/06\/JGO-COFB-juny-2-1024x547.jpg\" alt=\"JGO-COFB-juny (2)\" width=\"620\" height=\"331\" \/><\/a><figcaption id=\"caption-attachment-30984\" class=\"wp-caption-text\">De izquierda a derecha: Jordi Casas, secretario, N\u00faria Bosch, vicepresidenta, Jordi de Dalmases, presidente, Joan Calduch, tesorero, y Guillermo Bagar\u00eda, vicetesorero<\/figcaption><\/figure>\n<div>\n<p><b><div class=\"box shadow\">El Informe de Tesorer\u00eda<\/b>, que expuso el <b>tesorero del Colegio, Joan Calduch<\/b>, destac\u00f3 hechos relevantes tanto del presupuesto de los servicios de facturaci\u00f3n y entrega de recetas (SFLR) como del presupuesto institucional de 2016. En cuanto al primero, destacan la <b>reducci\u00f3n de gastos de facturaci\u00f3n y de mantenimiento de la estructura de la receta electr\u00f3nica<\/b> y <b>el incremento de ingresos provenientes de la cartera de servicios<\/b> (<a href=\"http:\/\/www.farmaceuticonline.com\/ca\/farmacies\/serveis-addicionals\/659-cancer-colon\">programa de cribado del c\u00e1ncer de colon<\/a> y <a href=\"http:\/\/www.farmaceuticonline.com\/ca\/farmacies\/serveis-addicionals\/661\">detecci\u00f3n precoz del VIH<\/a>).<\/p>\n<p>En cuanto al presupuesto institucional, destacan <b>el ajuste de la cuota complementaria a la cantidad presupuestada<\/b> el mes de diciembre (reducci\u00f3n de 0,09% a 0,061%), y en cuanto al <a href=\"http:\/\/www.infarma.es\/en\/web\/infarma-2017\">Congreso Infarma<\/a>, Calduch explic\u00f3 que el <b>balance global es muy positivo<\/b>. Asimismo, <b>se han seguido destinando recursos a formaci\u00f3n<\/b> presencial y no presencial y al <b>desarrollo profesional<\/b> de los colegiados.<\/p>\n<p>El presupuesto se liquid\u00f3 positivamente con un <b>super\u00e1vit de 1.487,59 \u20ac.<\/b> Las cifras presentadas por Tesorer\u00eda constatan que el COFB mantiene una\u00a0<b>tendencia positiva en el uso de los recursos colegiales y de las pol\u00edticas de optimizaci\u00f3n en la gesti\u00f3n<\/b>. <\/div><\/p>\n<\/div>\n<div>\n<div class=\"box shadow\">Previamente al Informe de Tesorer\u00eda, el <b>secretario del Colegio, Jordi Casas<\/b>, dio a conocer las <b>datos m\u00e1s relevantes de la Memoria de la gesti\u00f3n de la Junta de Gobierno del COFB.<\/b><\/p>\n<p>El Secretario empez\u00f3 su intervenci\u00f3n trasladando a los asistentes las cifras de 2016: el n\u00famero de colegiados, que ya supera los 8.600 profesionales, y c\u00f3mo se distribuyen por vocal\u00edas. A continuaci\u00f3n, explic\u00f3 la labor llevada a cabo por el Colegio a lo largo del pasado a\u00f1o. En primer lugar, <b>c\u00f3mo se est\u00e1 impulsando la transformaci\u00f3n digital del COFB:<\/b> aprovechando los cambios normativos, desde el Colegio se han impulsado varios proyectos en el \u00e1mbito tecnol\u00f3gico para mejorar los servicios y la relaci\u00f3n con los colegiados. En este contexto, <b>se est\u00e1 desarrollando el &quot;Portal de Tr\u00e1mites&quot; y la &quot;Carpeta del Colegiado&quot;.<\/b> Casas avanz\u00f3 que a medio plazo (2019), todo procedimiento de tramitaci\u00f3n deber\u00e1 ser electr\u00f3nico, destacando que la <b>tramitaci\u00f3n de expedientes<\/b> (durante 2016 se han tramitado un total de 3.139 expedientes que han generado m\u00e1s de 9.000 comunicaciones) <b>ser\u00e1 una de las gestiones que se incorporar\u00e1n al portal de tr\u00e1mites<\/b>, lo que permitir\u00e1 agilizar el procedimiento del alto volumen de documentos que se tramiten anualmente.<\/p>\n<p>Seguidamente, traslad\u00f3 que <b>se han atendido m\u00e1s de 125.000 consultas en los diversos departamentos del Colegio para dar respuesta a las necesidades de los colegiados<\/b> y que <b>se sigue trabajando por una formaci\u00f3n de calidad<\/b>, con 163 actividades formativas impartidas entre cursos presenciales, online y conferencias y 89 ediciones de cursos del portal formativo <a href=\"http:\/\/www.agorasanitaria.com\/ca\/web\/guest\">\u00c1gora Sanitaria<\/a>.<\/p>\n<p>El <b>COFB tambi\u00e9n vela por la excelencia en el ejercicio de la profesi\u00f3n<\/b>: Casas expuso los datos relativos al Servicio de Inspecci\u00f3n (1.487 Visitas de inspecci\u00f3n \/ asesoramiento) y las solicitudes de intervenci\u00f3n llevadas a cabo por la Comisi\u00f3n de Deontolog\u00eda (144). Otro dato relevante expuesto es el <b>consolidaci\u00f3n del sistema de receta electr\u00f3nica<\/b>: a fecha de cierre de 2016 se constata que <b>el 95% de recetas ya son electr\u00f3nicas<\/b>. Sin embargo, el Colegio tambi\u00e9n ha apostado por <b>potenciar la presencia en la red a trav\u00e9s de los distintos canales con el desarrollo de diferentes canales digitales<\/b>: <a href=\"http:\/\/farmaceutics.cofb.net\/\">web colegial<\/a>, <a href=\"http:\/\/www.cofb.org\/es\/web\/guest\/inici\/\">web institucional<\/a>, <a href=\"http:\/\/www.farmaceuticonline.com\/\">web de salud<\/a>, <a href=\"http:\/\/blog.cofb.cat\/els-col%C2%B7legiats-aproven-la-liquidacio-del-pressupost-del-2014\/\">Blog<\/a> y <a href=\"https:\/\/twitter.com\/farmaceuticsbcn\">Twitter<\/a>. Asimismo, <b>se ha fortalecido la comunicaci\u00f3n con los colegiados<\/b> con 52 boletines electr\u00f3nicos y 964 comunicaciones enviados por correo electr\u00f3nico para mantener informados a los colegiados de la actividad del Colegio y las novedades del sector, a\u00f1adiendo un dise\u00f1o renovado.<\/p>\n<p style=\"text-align: left;\">A nivel externo, el Secretario explic\u00f3 a los colegiados asistentes que <b>se ha querido seguir trasladando a la sociedad el valor y la actividad de la farmacia<\/b>: prueba de ello son las m\u00e1s de 1.260 apariciones en medios, las 320 peticiones de periodistas atendidas, las 49 notas de prensa enviadas y las 200 noticias publicadas en este Blog. Por \u00faltimo, Casas hizo menci\u00f3n al<b>apuesta que se est\u00e1 haciendo por herramientas pr\u00e1cticas para el colegiado: <\/b>la <b>bolsa de trabajo<\/b> ha gestionado 1.800 ofertas de trabajo con 666 candidatos inscritos y 12.947 CV enviados, y se han emitido y renovado 1.273<b> certificados digitales.<\/b><\/div>\n<p><div class=\"box shadow\">La \u00faltima parte de la Junta General Ordinaria se destin\u00f3 a trasladar <b>el Informe de Presidencia. Jordi de Dalmases<\/b>,<b> presidente del Colegio,<\/b> empez\u00f3 su intervenci\u00f3n repasando los temas de actualidad: la <b>puesta en marcha del Plan Estrat\u00e9gico del COFB<\/b> para impulsar profesionalmente a los farmac\u00e9uticos de todos los \u00e1mbitos de ejercicio como agentes de salud, las cifras m\u00e1s destacadas de la pasada edici\u00f3n de<b><a href=\"http:\/\/blog.cofb.cat\/category\/infarma-2015\/\">Infarma Barcelona 2017<\/a> <\/b>-que ha generado m\u00e1s de 500 repercusiones en los medios y el env\u00edo de 31 notas de prensa-, la <b>incorporaci\u00f3n del Colegio a la asociaci\u00f3n Intercolegial de Colegios Profesionales de Catalu\u00f1a <\/b>y la <b>puesta en marcha del <i>Protocolo de comunicaci\u00f3n entre primaria y comunitaria<\/i><\/b>, con la colaboraci\u00f3n de los coordinadores, fundamental en proyectos como \u00e9ste y que ayudan a garantizar r la presencia del farmac\u00e9utico en mesas de salud en todo el territorio.<\/p>\n<\/div>\n<div>\n<p>A continuaci\u00f3n, <b>Guillermo Bagar\u00eda<\/b>, <b>vicetesorero del COFB y responsable de Atenci\u00f3n Farmac\u00e9utica<\/b>, detall\u00f3 el<b>estado de los proyectos y servicios profesionales que llevan a cabo las farmacias<\/b>: <a href=\"http:\/\/www.farmaceuticonline.com\/ca\/farmacies\/serveis-addicionals\/661\">determinaci\u00f3n del riesgo por VIH<\/a>, <a href=\"http:\/\/www.farmaceuticonline.com\/ca\/farmacies\/serveis-addicionals\/659-cancer-colon\">detecci\u00f3n precoz del c\u00e1ncer de colon y recto<\/a>, <a href=\"http:\/\/www.farmaceuticonline.com\/ca\/farmacies\/serveis-addicionals\/664\">mantenimiento con metadona<\/a>, <a href=\"http:\/\/blog.cofb.cat\/els-farmaceutics-de-barcelona-participen-en-diferents-activitats-per-millorar-la-seva-qualitat-de-vida\/\">educaci\u00f3n sanitaria para la gente mayor<\/a>, <a href=\"http:\/\/www.farmaceuticonline.com\/ca\/farmacies\/serveis-addicionals\/662\">seguimiento farmacoterap\u00e9utico con SPD<\/a>, <a href=\"http:\/\/www.farmaceuticonline.com\/ca\/farmacies\/serveis-addicionals\/665\">deshabituaci\u00f3n tab\u00e1quica<\/a>, <a href=\"http:\/\/www.farmaceuticonline.com\/ca\/component\/content\/article\/20-varios\/712-farmacias-que-participan-en-programa-de-deteccion-del-riesgo-cardiovascular-a-10-anos\">detecci\u00f3n del rizo cardiovascular (Farmacardio),<\/a> <a href=\"http:\/\/blog.cofb.cat\/lajuntament-el-cofb-acorden-estendre-la-xarxa-de-radars\/\">acci\u00f3n comunitaria para las personas mayores (Radares)<\/a> y <a href=\"http:\/\/www.farmaceuticonline.com\/ca\/farmacies\/serveis-addicionals\/663\">intercambio de jeringuillas (PIX)<\/a>. Tambi\u00e9n explic\u00f3 la <b><a href=\"http:\/\/blog.cofb.cat\/dia-mundial-contra-el-cancer-de-colon-recte-xifres-de-la-prova-de-deteccio-precoc-amb-la-participacio-de-les-farmacies\/\">participaci\u00f3n en la Jornada en Sant Pau con pacientes y resto de agentes con motivo del D\u00eda Mundial del C\u00e1ncer de Colon<\/a> <\/b>y el estado del proyecto de <b><a href=\"http:\/\/blog.cofb.cat\/comenca-el-pilotatge-de-la-xarxa-de-farmacies-sentinelles-a-catalunya\/\">red de farmacias centinelas<\/a><\/b>, con implantaci\u00f3n prevista para el verano 2017 con 60 farmacias y una poblaci\u00f3n de 146.335 habitantes.<\/p>\n<p>Seguidamente<b> N\u00faria Bosch, vicepresidenta del Colegio y responsable de Comunicaci\u00f3n de la Junta de Govern<\/b>, explic\u00f3 el desarrollo de la <b><a href=\"http:\/\/www.farmaceuticonline.com\/ca\/component\/content\/article\/20-varios\/726-campana-para-la-prevencion-y-la-deteccion-precoz-de-los-riesgos-de-padecer-un-cancer-de-piel\">campa\u00f1a \u201cAntes de dejarte la piel, consulta\u201d<\/a><\/b> (<a href=\"http:\/\/blog.cofb.cat\/mes-de-2-000-persones-ja-han-anat-les-farmacies-per-prevenir-detectar-els-riscos-de-patir-un-cancer-de-pell\/\">participaci\u00f3n de m\u00e1s de 500 farmac\u00e9uticos participantes y m\u00e1s de 300 farmacias<\/a> y una <a href=\"http:\/\/blog.cofb.cat\/exit-de-participacio-de-la-carpa-informativa-de-la-campanya-per-la-prevencio-de-patir-un-cancer-de-pell\/\">carpa itinerante informativa que ha recorrido 11 ciudades de la provincia<\/a>). Esta iniciativa ha contado con una <b>campa\u00f1a de comunicaci\u00f3n<\/b> para trasladarla a la sociedad: se ha hecho difusi\u00f3n en medios locales gracias a la colaboraci\u00f3n de los coordinadores y de todos los farmac\u00e9uticos presentes en las carpas y se ha llevado a cabo una <b><a href=\"http:\/\/blog.cofb.cat\/mes-de-300-farmacies-de-barcelona-contribuiran-la-prevencio-deteccio-precoc-dels-riscos-de-patir-un-cancer-de-pell\/\">rueda de prensa el d\u00eda de la presentaci\u00f3n<\/a><\/b> <b>y notas de prensa<\/b> posteriores a Barcelona ciudad y territorio. Tambi\u00e9n se ha desarrollado en paralelo <b>una campa\u00f1a publicitaria y de art\u00edculos en prensa<\/b> <b>firmados por farmac\u00e9uticos y una fuerte presencia en las redes sociales<\/b>.<\/p>\n<p>Bosch tambi\u00e9n traslad\u00f3 a los asistentes que<b> la comunicaci\u00f3n<\/b>, tanto a colegiados como a farmac\u00e9uticos, otros profesionales sanitarios y la sociedad en general, <b>es uno de los puntos que se quiere potenciar en el marco del Plan Estrat\u00e9gico<\/b> que explicaba en primer t\u00e9rmino el Presidente. En cuanto a la comunicaci\u00f3n a los colegiados, se han introducido <b>mejoras en las comunicaciones<\/b> que se env\u00edan a los colegiados <b>y webinars para facilitar la formaci\u00f3n y el acceso a contenidos online<\/b>; en la comunicaci\u00f3n con la sociedad, se est\u00e1 trabajando en el <b>redise\u00f1o del <a href=\"http:\/\/www.cofb.org\/es\/web\/guest\/inici\/\">web instituciona<\/a>l<\/b> <b>y al potenciar la presencia en redes sociales, <\/b>la web de salud <b><a href=\"http:\/\/www.farmaceuticonline.com\/ca\/component\/content\/article\/20-varios\/726-campana-para-la-prevencion-y-la-deteccion-precoz-de-los-riesgos-de-padecer-un-cancer-de-piel\">Farmaceuticonline<\/a> se ha adaptado para m\u00f3viles<\/b> y se ha apostado por <b>dar continuidad de campa\u00f1as<\/b> que permitan contribuir a la mejora de la salud de la poblaci\u00f3n y comunicar valor profesional del farmac\u00e9utico.<\/p>\n<p>El Presidente traslad\u00f3 a continuaci\u00f3n cu\u00e1l es la <b>situaci\u00f3n financiera:<\/b> el estado de las <b>dos reclamaciones de intereses<\/b> interpuestas con las cantidades depositadas, la situaci\u00f3n actual de cobro y la compensaci\u00f3n mensual de costes financieros. Cedi\u00f3 entonces la palabra al secretario, Jordi Casas, que explic\u00f3 en qu\u00e9 punto se encuentra el <b>PLANUC (Plan nacional de urgencias de Catalu\u00f1a)<\/b> y c\u00f3mo la reorganizaci\u00f3n de urgencias afecta a las guardias. Seguidamente, el Presidente hizo un repaso a las<b> novedades legislativas<\/b>: <b>SEVEM <\/b>(Sistema Espa\u00f1ol Verificaci\u00f3n de Medicamentos), el <b>Proyecto RD financiaci\u00f3n y precios de los medicamentos y Productos Sanitarios<\/b> (PS) 18\/09\/2015 y el \u00a0<b>Test de proporcionalidad<\/b>.<\/p>\n<p>A su vez, el tesorero, Joan Calduch, reanud\u00f3 la palabra para explicar las novedades relativas al Consejo de Colegios Farmac\u00e9uticos de Catalunya, de lo que es vicetesorero: el porqu\u00e9 de la <b>migraci\u00f3n, la mejora de la tecnolog\u00eda y calidad de la Red (XCCFC) y cu\u00e1l es el Plan de Sistemas del Consejo<\/b>. Por \u00faltimo, el Presidente termin\u00f3 el Informe de Presidencia dando a conocer los <a href=\"http:\/\/blog.cofb.cat\/el-cofb-el-consell-premiats-amb-quatre-guardons-per-correo-farmaceutico\/\">4 galardones recibidos en los Premios de Correo Farmac\u00e9utico<\/a> por los proyectos <a href=\"http:\/\/blog.cofb.cat\/mes-de-5500-persones-participen-en-la-campanya-de-prevencio-del-cancer-de-pell-les-farmacies\/\">\u201cAntes de dejarte la piel, consulta\u201d,<\/a> <a href=\"http:\/\/blog.cofb.cat\/el-cof-de-barcelona-edita-un-formulari-per-personalitzar-els-tractaments-pal%C2%B7liatius-dels-pacients\/\">Formulario de soporte a paliativos<\/a>, <a href=\"http:\/\/blog.cofb.cat\/les-farmacies-participen-en-la-campanya-pren-te-el-pols\/\">&#039;T\u00f3mate el pulso&#039;<\/a> y <a href=\"http:\/\/blog.cofb.cat\/usuaris-valoren-amb-un-95-el-programa-de-deteccio-precoc-de-cancer-de-colon\/\">Estudio para analizar los cribados de c\u00e1ncer de colon en farmacia. <\/div><\/a><\/p>\n<\/div>\n<p><span style=\"color: #888888;\"><b>Cada a\u00f1o, el Colegio lleva a cabo dos Juntas Generales relacionadas con el presupuesto COFB en las que se presenta a los colegiados la liquidaci\u00f3n del a\u00f1o anterior (Junta del mes de junio) y la propuesta de presupuesto para el a\u00f1o siguiente (Junta de diciembre). La aprobaci\u00f3n de los presupuestos se somete a la votaci\u00f3n de los colegiados que asisten.<\/b><\/span><\/p>\n<p><b>Quiz\u00e1s tambi\u00e9n te interesa (v\u00eda Blog):<\/b><\/p>\n<ul>\n<li><a href=\"http:\/\/blog.cofb.cat\/laposta-pel-desplegament-de-projectes-assistencials-el-desenvolupament-professional-claus-del-pressupost-2017\/\">La apuesta por el despliegue de proyectos asistenciales y el desarrollo profesional, claves del presupuesto 2017<\/a><\/li>\n<li><a href=\"http:\/\/blog.cofb.cat\/junta-general-ordinaria-els-col%C2%B7legiats-aproven-la-liquidacio-del-pressupost-del-2015-2\/\">Junta General Ordinaria: los colegiados aprueban la liquidaci\u00f3n del presupuesto de 2015<\/a><\/li>\n<li><a href=\"http:\/\/blog.cofb.cat\/saprova-la-proposta-de-pressupostos-del-cofb-per-al-2016\/\">Se aprueba la propuesta de presupuestos del COFB para 2016<\/a><\/li>\n<li><a href=\"http:\/\/blog.cofb.cat\/els-col%C2%B7legiats-aproven-la-liquidacio-del-pressupost-del-2014\/\">Los colegiados aprueban la liquidaci\u00f3n del presupuesto de 2014<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>El equipo econ\u00f3mico de la Junta de Gobierno del Colegio present\u00f3 en la Junta General Ordinaria celebrada ayer, 15 de junio, la liquidaci\u00f3n del presupuesto del ejercicio 2016, recibiendo la aprobaci\u00f3n por unanimidad de los colegiados asistentes. Cada a\u00f1o, el Colegio lleva a cabo dos Juntas Generales relacionadas con el presupuesto [\u2026]<\/p>","protected":false},"author":1,"featured_media":30984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[57],"tags":[2442,2176,18,19,692,28,419,420,118],"class_list":["post-30942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mon-collegial","tag-abans-de-deixar-thi-la-pell","tag-cartera-de-serveis","tag-cofb","tag-collegi-de-farmaceutics-de-barcelona","tag-collegiats","tag-infarma","tag-junta-general","tag-junta-general-ordinaria","tag-serveis-professionals"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016<\/title>\n<meta name=\"description\" content=\"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col\u00b7legiats-aproven-la-liquidacio-del-pressupost-2016\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016\" \/>\n<meta property=\"og:description\" content=\"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col\u00b7legiats-aproven-la-liquidacio-del-pressupost-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-19T12:39:20+00:00\" \/>\n<meta name=\"author\" content=\"wpAdminCofbOrg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:site\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpAdminCofbOrg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/\"},\"author\":{\"name\":\"wpAdminCofbOrg\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\"},\"headline\":\"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016\",\"datePublished\":\"2017-06-19T12:39:20+00:00\",\"dateModified\":\"2017-06-19T12:39:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/\"},\"wordCount\":1740,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Abans de deixar-t'hi la pell\",\"cartera de serveis\",\"COFB\",\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"col\u00b7legiats\",\"Infarma\",\"Junta General\",\"Junta General Ordin\u00e0ria\",\"Serveis professionals\"],\"articleSection\":[\"M\u00f3n col\u00b7legial\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/\",\"url\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/\",\"name\":\"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016\",\"isPartOf\":{\"@id\":\"https:\/\/www.cofb.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2017-06-19T12:39:20+00:00\",\"dateModified\":\"2017-06-19T12:39:20+00:00\",\"description\":\"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016\",\"breadcrumb\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.cofb.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cofb.org\/#website\",\"url\":\"https:\/\/www.cofb.org\/\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cofb.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cofb.org\/#organization\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"url\":\"https:\/\/www.cofb.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"contentUrl\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"width\":500,\"height\":105,\"caption\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\"},\"image\":{\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\",\"https:\/\/twitter.com\/farmaceuticsbcn\",\"https:\/\/www.instagram.com\/farmaceuticsbcn\/\",\"https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\",\"name\":\"wpAdminCofbOrg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"caption\":\"wpAdminCofbOrg\"},\"sameAs\":[\"http:\/\/192.168.64.122\/wordpress\"],\"url\":\"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016","description":"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col\u00b7legiats-aproven-la-liquidacio-del-pressupost-2016\/","og_locale":"es_ES","og_type":"article","og_title":"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016","og_description":"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016","og_url":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col\u00b7legiats-aproven-la-liquidacio-del-pressupost-2016\/","og_site_name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","article_publisher":"https:\/\/www.facebook.com\/farmaceuticsbcn\/","article_published_time":"2017-06-19T12:39:20+00:00","author":"wpAdminCofbOrg","twitter_card":"summary_large_image","twitter_creator":"@farmaceuticsbcn","twitter_site":"@farmaceuticsbcn","twitter_misc":{"Escrito por":"wpAdminCofbOrg","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#article","isPartOf":{"@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/"},"author":{"name":"wpAdminCofbOrg","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb"},"headline":"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016","datePublished":"2017-06-19T12:39:20+00:00","dateModified":"2017-06-19T12:39:20+00:00","mainEntityOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/"},"wordCount":1740,"commentCount":0,"publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"image":{"@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#primaryimage"},"thumbnailUrl":"","keywords":["Abans de deixar-t'hi la pell","cartera de serveis","COFB","Col\u00b7legi de Farmac\u00e8utics de Barcelona","col\u00b7legiats","Infarma","Junta General","Junta General Ordin\u00e0ria","Serveis professionals"],"articleSection":["M\u00f3n col\u00b7legial"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/","url":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/","name":"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016","isPartOf":{"@id":"https:\/\/www.cofb.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#primaryimage"},"image":{"@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#primaryimage"},"thumbnailUrl":"","datePublished":"2017-06-19T12:39:20+00:00","dateModified":"2017-06-19T12:39:20+00:00","description":"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016","breadcrumb":{"@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/novaorg.cofb.net\/2017\/06\/19\/junta-general-ordinaria-els-col%c2%b7legiats-aproven-la-liquidacio-del-pressupost-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cofb.org\/"},{"@type":"ListItem","position":2,"name":"Junta General Ordin\u00e0ria: els col\u00b7legiats aproven la liquidaci\u00f3 del pressupost 2016"}]},{"@type":"WebSite","@id":"https:\/\/www.cofb.org\/#website","url":"https:\/\/www.cofb.org\/","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","description":"","publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cofb.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.cofb.org\/#organization","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","url":"https:\/\/www.cofb.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","contentUrl":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","width":500,"height":105,"caption":"Col\u00b7legi de Farmac\u00e8utics de Barcelona"},"image":{"@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/farmaceuticsbcn\/","https:\/\/twitter.com\/farmaceuticsbcn","https:\/\/www.instagram.com\/farmaceuticsbcn\/","https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/"]},{"@type":"Person","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb","name":"wpAdminCofbOrg","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","caption":"wpAdminCofbOrg"},"sameAs":["http:\/\/192.168.64.122\/wordpress"],"url":"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"wpAdminCofbOrg","author_link":"https:\/\/www.cofb.org\/es\/author\/wpadmincofborg\/"},"uagb_comment_info":0,"uagb_excerpt":"L\u2019equip econ\u00f2mic de la Junta de Govern del Col\u00b7legi va presentar a la Junta General Ordin\u00e0ria celebrada ahir, 15 de juny, la liquidaci\u00f3 del pressupost de l\u2019exercici del 2016, rebent l\u2019aprovaci\u00f3 per unanimitat dels col\u00b7legiats assistents. Cada any, el Col\u00b7legi duu a terme dues Juntes Generals relacionades amb el pressupost [&hellip;]","_links":{"self":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts\/30942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/comments?post=30942"}],"version-history":[{"count":0,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/posts\/30942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/media?parent=30942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/categories?post=30942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cofb.org\/es\/wp-json\/wp\/v2\/tags?post=30942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}