{"id":77472,"date":"2015-03-26T09:02:00","date_gmt":"2015-03-26T09:02:00","guid":{"rendered":"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/"},"modified":"2015-03-26T09:02:00","modified_gmt":"2015-03-26T09:02:00","slug":"la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis","status":"publish","type":"post","link":"https:\/\/www.cofb.org\/ca\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/","title":{"rendered":"La distribuci\u00f3n farmac\u00e9utica ha sido capaz de mantener la calidad del servicio en un entorno marcado por la crisis"},"content":{"rendered":"<p>\u00a0<\/p>\n<ul>\n<li><strong>Los mayoristas exponen las acciones desarrolladas para contribuir a que las farmacias superen sus dificultades econ\u00f3micas, dirigidas a la mejora de su gesti\u00f3n <\/strong><\/li>\n<li><strong>Los representantes de las principales distribuidoras condenan las pr\u00e1cticas ilegales en la venta de medicamentos y defienden como prioridad dar respuesta a la demanda sanitaria de la poblaci\u00f3n<\/strong><br \/>\u00a0<\/li>\n<\/ul>\n<p><span lang=\"ES\"><em>Barcelona, 26 de marzo de 2015.- <\/em>La mesa redonda sobre \u2018Respuestas de la distribuci\u00f3n a la crisis del sector\u2019, celebrada el 26 de marzo en el marco del Congreso Infarma 2015, ha puesto de manifiesto que, a pesar de que el sector de los mayoristas farmac\u00e9uticos tambi\u00e9n padece la situaci\u00f3n de dificultad econ\u00f3mica, ha realizado un gran esfuerzo por que la calidad del servicio prestado a las oficinas de farmacia no se haya resentido. \u201cSupone un logro el haber sido capaces de mantener las condiciones de servicio equivalentes a los a\u00f1os previos a la crisis\u201d, ha afirmado C\u00e9sar Mart\u00ednez, presidente de Alliance Healthcare.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">Tambi\u00e9n ha insistido en la idea de que la distribuci\u00f3n ha sabido dar el mejor servicio ante una situaci\u00f3n econ\u00f3mica muy complicada Carlos Coves, presidente de Hefame: \u201cNo hay que olvidar que el modelo de farmacia, uno de los mejores del mundo, no est\u00e1 en crisis, sino que sufre las acciones de un Gobierno que s\u00ed lo est\u00e1 y que carga sus problemas econ\u00f3micos sobre el sistema farmac\u00e9utico\u201d, ha subrayado.\u00a0 <\/p>\n<p><\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">Juan Ignacio G\u00fcenechea, vicepresidente de Cofares, coincide con Mart\u00ednez y Coves al considerar que la distribuci\u00f3n ha ejercido un papel muy importante en lo que respecta al mantenimiento financiero de las oficinas de farmacia, \u201cen un entorno muy dif\u00edcil de gestionar\u201d, no s\u00f3lo en lo que respecta a ayudarlas a hacer frente a los impagos. \u201cNuestro objetivo ha sido dar respuesta a sus necesidades y lo hemos hecho de forma r\u00e1pida\u201d, ha apuntado. Del mismo modo, el presidente de Fedefarma, Vicen\u00e7 Calduch, ha resaltado que la cooperativa trabaja por facilitar a las farmacias la superaci\u00f3n de la crisis. \u201cEstamos al lado de la soluci\u00f3n, y no del problema\u201d, ha precisado.<\/p>\n<p><\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">A la doble pregunta planteada por el moderador, Antonio Torres, presidente de la Federaci\u00f3n de Asociaciones de Farmacias de Catalu\u00f1a (FEFAC), sobre qu\u00e9 acciones han llevado a cabo para contribuir a que las farmacias reduzcan sus costes internos y aumenten sus ingresos, los diferentes representantes de las distribuidoras con m\u00e1s peso del pa\u00eds han expuesto medidas que van en el mismo sentido \u201caunque de maneras diferentes\u201d, tal como ha expresado el vicepresidente de Hefame.<\/p>\n<p><\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">Los servicios implantados por las diferentes distribuidoras van en la l\u00ednea de apoyar a las farmacias en la mejora de su gesti\u00f3n y en ayudarlas a vender, a trav\u00e9s de estrategias de optimizaci\u00f3n de stocks, an\u00e1lisis de las l\u00edneas de productos a potenciar, la marca propia o herramientas inform\u00e1ticas para la mejora de la gesti\u00f3n interna. Tambi\u00e9n han destacado los servicios de prevenci\u00f3n y detecci\u00f3n de enfermedades, as\u00ed como la formaci\u00f3n y actividades de Responsabilidad Social Corporativa.<\/p>\n<p><\/span><\/p>\n<p class=\"MsoNormal\"><u><b><span lang=\"ES\">Posicionamiento sobre pr\u00e1cticas il\u00edcitas de distribuci\u00f3n<\/span><\/b><\/u><b><span lang=\"ES\"><\/p>\n<p><\/span><\/b><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">Torres ha pedido a los ponentes su posicionamiento ante las pr\u00e1cticas de distribuci\u00f3n que perjudican al sector, tanto las legales, como la importaci\u00f3n paralela, como las ilegales, concretamente, la denominada \u2018distribuci\u00f3n inversa\u2019, por la que el medicamento sale del circuito establecido para ser revendido posteriormente en el exterior.<\/p>\n<p><\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">Respecto al comercio paralelo, promovido por algunos pa\u00edses como Alemania, cuyo gobierno incentiva a las oficinas de farmacia la dispensaci\u00f3n de medicamentos importados de otros pa\u00edses, Calduch ha subrayado que, aunque en principio son l\u00edcitas desde el punto de vista legal, las cooperativas deben tener como prioridad que el destino del producto a distribuir sean las oficinas de farmacia, con el fin de atender la demanda sanitaria de la poblaci\u00f3n del territorio nacional.<\/p>\n<p><\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">G\u00fcenechea ha apuntado que estas pr\u00e1cticas se producen siempre que hay mercados nacionales con diferentes precios, y que vienen inducidas por la demanda de los pa\u00edses y el propio inter\u00e9s de los laboratorios de que se lleven a cabo estas importaciones. Otro tipo diferente de acciones, que hay que diferenciar claramente, son las que constituyen una ilegalidad y \u201cque perjudican el ADN de la farmacia\u201d, seg\u00fan el vicepresidente de Cofares, que comparte con el resto de ponentes el firme rechazo a estas pr\u00e1cticas.<\/p>\n<p><\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">A este respecto, el presidente de Hefame ha remarcado que la distribuci\u00f3n trabaja con el Gobierno, la Agencia Espa\u00f1ola del Medicamento y Productos Sanitarios y Farmaindustria para poner fin a estos casos de distribuci\u00f3n ilegal y evitar un desabastecimiento que pueda repercutir sobre el acceso de los ciudadanos a su medicaci\u00f3n.<\/p>\n<p><\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">Otra de las preocupaciones que se han puesto sobre la mesa es la derivada del goteo de salidas de productos de la oficina de farmacia hacia otros canales como el hospitalario. As\u00ed lo ha remarcado el vicepresidente de Cofares, que considera que hay que buscar f\u00f3rmulas para ser capaces de dar respuesta al reto de devolver estos productos al canal farmacia y mantenerlos en \u00e9l, y en este sentido considera que la distribuci\u00f3n puede aportar un valor a\u00f1adido en las negociaciones con la Administraci\u00f3n para alcanzar este objetivo.<\/p>\n<p><\/span><\/p>\n<p class=\"MsoNormal\"><b><span lang=\"ES\">Acerca de INFARMA <\/p>\n<p><\/span><\/b><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">El XXVII Congreso y Sal\u00f3n Europeo de Farmacia INFARMA, punto de encuentro del sector farmac\u00e9utico, tiene lugar del 24 al 26 de marzo en el recinto ferial de Gran Via de Barcelona y est\u00e1 organizado por el Colegio de Farmac\u00e9uticos de Madrid y el Col\u00b7legi de Farmac\u00e8utics de Barcelona con la colaboraci\u00f3n de Interalia. Durante tres d\u00edas m\u00e1s de 220 ponentes de \u00e1mbito nacional e internacional se dar\u00e1n cita para hablar, en las 10 mesas de debate y m\u00e1s de 60 aulas activas, sobre los nuevos servicios que ofrecen las farmacias al paciente de forma creciente, as\u00ed como la actualidad y las perspectivas del sector, bajo el lema escogido para esta edici\u00f3n: \u201cOrientados a la acci\u00f3n. Experiencias para mejorar la farmacia des del presente\u201d.<\/span><\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p><strong>INFARMA BARCELONA 2015 EN CIFRAS<\/strong><\/p>\n<p>Programa<\/p>\n<ul>\n<li>M\u00e1s de 60 aulas activas y 10 mesas redondas<\/li>\n<li>M\u00e1s de 220 ponentes<\/li>\n<\/ul>\n<p>Previsi\u00f3n de visitantes<\/p>\n<ul>\n<li>M\u00e1s de 25.000 profesionales<\/li>\n<li>335 laboratorios y empresas expositoras<\/li>\n<li>1.100 marcas<\/li>\n<\/ul>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p><strong>Para m\u00e1s informaci\u00f3n:<br \/><\/strong><span>Departamento de Comunicaci\u00f3n<\/span><br \/><span>Infarma 2015\u00a0<\/span><a href=\"http:\/\/www.infarma.es.\/\" target=\"_blank\" rel=\"noopener\">www.infarma.es.<\/a><span>\u00a0Y tambi\u00e9n en Twitter.<\/span><br \/><span>Tel. 93 244 07 28 \/ 18<\/span><br \/><a>premsa@cofb.net<\/a><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\"><\/p>\n<p><\/span><\/p>\n<p>\u00a0Los mayoristas exponen las acciones desarrolladas para contribuir a que las farmacias superen sus dificultades econ\u00f3micas, dirigidas a la mejora de su gesti\u00f3n Los representantes de las principales distribuidoras condenan las pr\u00e1cticas ilegales en la venta de medicamentos y defienden como prioridad dar respuesta a la demanda sanitaria de la poblaci\u00f3n\u00a0Barcelona, 26 de marzo de 2015.- La mesa redonda sobre \u2018Respuestas de la distribuci\u00f3n a la crisis del sector\u2019, celebrada el 26 de marzo en el marco del Congreso Infarma 2015, ha puesto de manifiesto que, a pesar de que el sector de los mayoristas farmac\u00e9uticos tambi\u00e9n padece la situaci\u00f3n de dificultad econ\u00f3mica, ha realizado un gran esfuerzo por que la calidad del servicio prestado a las oficinas de farmacia no se haya resentido. \u201cSupone un logro el haber sido capaces de mantener las condiciones de servicio equivalentes a los a\u00f1os previos a la crisis\u201d, ha afirmado C\u00e9sar Mart\u00ednez, presidente de Alliance Healthcare.Tambi\u00e9n ha insistido en la idea de que la distribuci\u00f3n ha sabido dar el mejor servicio ante una situaci\u00f3n econ\u00f3mica muy complicada Carlos Coves, presidente de Hefame: \u201cNo hay que olvidar que el modelo de farmacia, uno de los mejores del mundo, no est\u00e1 en crisis, sino que sufre las acciones de un Gobierno que s\u00ed lo est\u00e1 y que carga sus problemas econ\u00f3micos sobre el sistema farmac\u00e9utico\u201d, ha subrayado.\u00a0   Juan Ignacio G\u00fcenechea, vicepresidente de Cofares, coincide con Mart\u00ednez y Coves al considerar que la distribuci\u00f3n ha ejercido un papel muy importante en lo que respecta al mantenimiento financiero de las oficinas de farmacia, \u201cen un entorno muy dif\u00edcil de gestionar\u201d, no s\u00f3lo en lo que respecta a ayudarlas a hacer frente a los impagos. \u201cNuestro objetivo ha sido dar respuesta a sus necesidades y lo hemos hecho de forma r\u00e1pida\u201d, ha apuntado. Del mismo modo, el presidente de Fedefarma, Vicen\u00e7 Calduch, ha resaltado que la cooperativa trabaja por facilitar a las farmacias la superaci\u00f3n de la crisis. \u201cEstamos al lado de la soluci\u00f3n, y no del problema\u201d, ha precisado.  A la doble pregunta planteada por el moderador, Antonio Torres, presidente de la Federaci\u00f3n de Asociaciones de Farmacias de Catalu\u00f1a (FEFAC), sobre qu\u00e9 acciones han llevado a cabo para contribuir a que las farmacias reduzcan sus costes internos y aumenten sus ingresos, los diferentes representantes de las distribuidoras con m\u00e1s peso del pa\u00eds han expuesto medidas que van en el mismo sentido \u201caunque de maneras diferentes\u201d, tal como ha expresado el vicepresidente de Hefame.  Los servicios implantados por las diferentes distribuidoras van en la l\u00ednea de apoyar a las farmacias en la mejora de su gesti\u00f3n y en ayudarlas a vender, a trav\u00e9s de estrategias de optimizaci\u00f3n de stocks, an\u00e1lisis de las l\u00edneas de productos a potenciar, la marca propia o herramientas inform\u00e1ticas para la mejora de la gesti\u00f3n interna. Tambi\u00e9n han destacado los servicios de prevenci\u00f3n y detecci\u00f3n de enfermedades, as\u00ed como la formaci\u00f3n y actividades de Responsabilidad Social Corporativa.  Posicionamiento sobre pr\u00e1cticas il\u00edcitas de distribuci\u00f3n  Torres ha pedido a los ponentes su posicionamiento ante las pr\u00e1cticas de distribuci\u00f3n que perjudican al sector, tanto las legales, como la importaci\u00f3n paralela, como las ilegales, concretamente, la denominada \u2018distribuci\u00f3n inversa\u2019, por la que el medicamento sale del circuito establecido para ser revendido posteriormente en el exterior.  Respecto al comercio paralelo, promovido por algunos pa\u00edses como Alemania, cuyo gobierno incentiva a las oficinas de farmacia la dispensaci\u00f3n de medicamentos importados de otros pa\u00edses, Calduch ha subrayado que, aunque en principio son l\u00edcitas desde el punto de vista legal, las cooperativas deben tener como prioridad que el destino del producto a distribuir sean las oficinas de farmacia, con el fin de atender la demanda sanitaria de la poblaci\u00f3n del territorio nacional.  G\u00fcenechea ha apuntado que estas pr\u00e1cticas se producen siempre que hay mercados nacionales con diferentes precios, y que vienen inducidas por la demanda de los pa\u00edses y el propio inter\u00e9s de los laboratorios de que se lleven a cabo estas importaciones. Otro tipo diferente de acciones, que hay que diferenciar claramente, son las que constituyen una ilegalidad y \u201cque perjudican el ADN de la farmacia\u201d, seg\u00fan el vicepresidente de Cofares, que comparte con el resto de ponentes el firme rechazo a estas pr\u00e1cticas.  A este respecto, el presidente de Hefame ha remarcado que la distribuci\u00f3n trabaja con el Gobierno, la Agencia Espa\u00f1ola del Medicamento y Productos Sanitarios y Farmaindustria para poner fin a estos casos de distribuci\u00f3n ilegal y evitar un desabastecimiento que pueda repercutir sobre el acceso de los ciudadanos a su medicaci\u00f3n.  Otra de las preocupaciones que se han puesto sobre la mesa es la derivada del goteo de salidas de productos de la oficina de farmacia hacia otros canales como el hospitalario. As\u00ed lo ha remarcado el vicepresidente de Cofares, que considera que hay que buscar f\u00f3rmulas para ser capaces de dar respuesta al reto de devolver estos productos al canal farmacia y mantenerlos en \u00e9l, y en este sentido considera que la distribuci\u00f3n puede aportar un valor a\u00f1adido en las negociaciones con la Administraci\u00f3n para alcanzar este objetivo.  Acerca de INFARMA   El XXVII Congreso y Sal\u00f3n Europeo de Farmacia INFARMA, punto de encuentro del sector farmac\u00e9utico, tiene lugar del 24 al 26 de marzo en el recinto ferial de Gran Via de Barcelona y est\u00e1 organizado por el Colegio de Farmac\u00e9uticos de Madrid y el Col\u00b7legi de Farmac\u00e8utics de Barcelona con la colaboraci\u00f3n de Interalia. Durante tres d\u00edas m\u00e1s de 220 ponentes de \u00e1mbito nacional e internacional se dar\u00e1n cita para hablar, en las 10 mesas de debate y m\u00e1s de 60 aulas activas, sobre los nuevos servicios que ofrecen las farmacias al paciente de forma creciente, as\u00ed como la actualidad y las perspectivas del sector, bajo el lema escogido para esta edici\u00f3n: \u201cOrientados a la acci\u00f3n. Experiencias para mejorar la farmacia des del presente\u201d.\u00a0INFARMA BARCELONA 2015 EN CIFRASProgramaM\u00e1s de 60 aulas activas y 10 mesas redondasM\u00e1s de 220 ponentesPrevisi\u00f3n de visitantesM\u00e1s de 25.000 profesionales335 laboratorios y empresas expositoras1.100 marcas\u00a0Para m\u00e1s informaci\u00f3n:Departamento de Comunicaci\u00f3nInfarma 2015\u00a0www.infarma.es.\u00a0Y tambi\u00e9n en Twitter.Tel. 93 244 07 28 \/ 18premsa@cofb.net\u00a0\u00a0COFB.ORG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Los mayoristas exponen las acciones desarrolladas para contribuir a que las farmacias superen sus dificultades econ\u00f3micas, dirigidas a la mejora de su gesti\u00f3n Los representantes de las principales distribuidoras condenan las pr\u00e1cticas ilegales en la venta de medicamentos y defienden como prioridad dar respuesta a la demanda sanitaria de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1060,1066],"tags":[],"class_list":["post-77472","post","type-post","status-publish","format-standard","hentry","category-notes-premsa","category-sense-categoria-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La distribuci\u00f3n farmac\u00e9utica ha sido capaz de mantener la calidad del servicio en un entorno marcado por la crisis - Col\u00b7legi de Farmac\u00e8utics de Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La distribuci\u00f3n farmac\u00e9utica ha sido capaz de mantener la calidad del servicio en un entorno marcado por la crisis - Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Los mayoristas exponen las acciones desarrolladas para contribuir a que las farmacias superen sus dificultades econ\u00f3micas, dirigidas a la mejora de su gesti\u00f3n Los representantes de las principales distribuidoras condenan las pr\u00e1cticas ilegales en la venta de medicamentos y defienden como prioridad dar respuesta a la demanda sanitaria de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-26T09:02:00+00:00\" \/>\n<meta name=\"author\" content=\"wpAdminCofbOrg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:site\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpAdminCofbOrg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/\"},\"author\":{\"name\":\"wpAdminCofbOrg\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\"},\"headline\":\"La distribuci\u00f3n farmac\u00e9utica ha sido capaz de mantener la calidad del servicio en un entorno marcado por la crisis\",\"datePublished\":\"2015-03-26T09:02:00+00:00\",\"dateModified\":\"2015-03-26T09:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/\"},\"wordCount\":2187,\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"articleSection\":[\"Notes de premsa\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/\",\"url\":\"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/\",\"name\":\"La distribuci\u00f3n farmac\u00e9utica ha sido capaz de mantener la calidad del servicio en un entorno marcado por la crisis - Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.cofb.org\/#website\"},\"datePublished\":\"2015-03-26T09:02:00+00:00\",\"dateModified\":\"2015-03-26T09:02:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.cofb.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La distribuci\u00f3n farmac\u00e9utica ha sido capaz de mantener la calidad del servicio en un entorno marcado por la crisis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cofb.org\/#website\",\"url\":\"https:\/\/www.cofb.org\/\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cofb.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cofb.org\/#organization\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"url\":\"https:\/\/www.cofb.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"contentUrl\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"width\":500,\"height\":105,\"caption\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\"},\"image\":{\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\",\"https:\/\/twitter.com\/farmaceuticsbcn\",\"https:\/\/www.instagram.com\/farmaceuticsbcn\/\",\"https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\",\"name\":\"wpAdminCofbOrg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"caption\":\"wpAdminCofbOrg\"},\"sameAs\":[\"http:\/\/192.168.64.122\/wordpress\"],\"url\":\"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La distribuci\u00f3n farmac\u00e9utica ha sido capaz de mantener la calidad del servicio en un entorno marcado por la crisis - Col\u00b7legi de Farmac\u00e8utics de Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/","og_locale":"ca_ES","og_type":"article","og_title":"La distribuci\u00f3n farmac\u00e9utica ha sido capaz de mantener la calidad del servicio en un entorno marcado por la crisis - Col\u00b7legi de Farmac\u00e8utics de Barcelona","og_description":"\u00a0 Los mayoristas exponen las acciones desarrolladas para contribuir a que las farmacias superen sus dificultades econ\u00f3micas, dirigidas a la mejora de su gesti\u00f3n Los representantes de las principales distribuidoras condenan las pr\u00e1cticas ilegales en la venta de medicamentos y defienden como prioridad dar respuesta a la demanda sanitaria de [&hellip;]","og_url":"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/","og_site_name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","article_publisher":"https:\/\/www.facebook.com\/farmaceuticsbcn\/","article_published_time":"2015-03-26T09:02:00+00:00","author":"wpAdminCofbOrg","twitter_card":"summary_large_image","twitter_creator":"@farmaceuticsbcn","twitter_site":"@farmaceuticsbcn","twitter_misc":{"Escrit per":"wpAdminCofbOrg","Temps estimat de lectura":"11 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/#article","isPartOf":{"@id":"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/"},"author":{"name":"wpAdminCofbOrg","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb"},"headline":"La distribuci\u00f3n farmac\u00e9utica ha sido capaz de mantener la calidad del servicio en un entorno marcado por la crisis","datePublished":"2015-03-26T09:02:00+00:00","dateModified":"2015-03-26T09:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/"},"wordCount":2187,"publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"articleSection":["Notes de premsa"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/","url":"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/","name":"La distribuci\u00f3n farmac\u00e9utica ha sido capaz de mantener la calidad del servicio en un entorno marcado por la crisis - Col\u00b7legi de Farmac\u00e8utics de Barcelona","isPartOf":{"@id":"https:\/\/www.cofb.org\/#website"},"datePublished":"2015-03-26T09:02:00+00:00","dateModified":"2015-03-26T09:02:00+00:00","breadcrumb":{"@id":"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/novaorg.cofb.net\/2015\/03\/26\/la-distribucion-farmaceutica-ha-sido-capaz-de-mantener-la-calidad-del-servicio-en-un-entorno-marcado-por-la-crisis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cofb.org\/"},{"@type":"ListItem","position":2,"name":"La distribuci\u00f3n farmac\u00e9utica ha sido capaz de mantener la calidad del servicio en un entorno marcado por la crisis"}]},{"@type":"WebSite","@id":"https:\/\/www.cofb.org\/#website","url":"https:\/\/www.cofb.org\/","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","description":"","publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cofb.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.cofb.org\/#organization","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","url":"https:\/\/www.cofb.org\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","contentUrl":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","width":500,"height":105,"caption":"Col\u00b7legi de Farmac\u00e8utics de Barcelona"},"image":{"@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/farmaceuticsbcn\/","https:\/\/twitter.com\/farmaceuticsbcn","https:\/\/www.instagram.com\/farmaceuticsbcn\/","https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/"]},{"@type":"Person","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb","name":"wpAdminCofbOrg","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","caption":"wpAdminCofbOrg"},"sameAs":["http:\/\/192.168.64.122\/wordpress"],"url":"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"wpAdminCofbOrg","author_link":"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00a0 Los mayoristas exponen las acciones desarrolladas para contribuir a que las farmacias superen sus dificultades econ\u00f3micas, dirigidas a la mejora de su gesti\u00f3n Los representantes de las principales distribuidoras condenan las pr\u00e1cticas ilegales en la venta de medicamentos y defienden como prioridad dar respuesta a la demanda sanitaria de [&hellip;]","_links":{"self":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts\/77472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/comments?post=77472"}],"version-history":[{"count":0,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts\/77472\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/media?parent=77472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/categories?post=77472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/tags?post=77472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}