{"id":77460,"date":"2015-04-10T15:30:00","date_gmt":"2015-04-10T15:30:00","guid":{"rendered":"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/"},"modified":"2015-04-10T15:30:00","modified_gmt":"2015-04-10T15:30:00","slug":"los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica","status":"publish","type":"post","link":"https:\/\/www.cofb.org\/ca\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/","title":{"rendered":"&#8220;Los complementos alimenticios deben estar sustentados por la evidencia cient\u00edfica&#8221;"},"content":{"rendered":"<p>\u00a0<\/p>\n<ul>\n<li><strong>La EFSA es el organismo encargado de autorizar un Health Claim y validar sus propiedades beneficiosas seg\u00fan los resultados cient\u00edficos presentados<\/strong><\/li>\n<li><strong>Desde el COF de Barcelona se est\u00e1 impulsando la creaci\u00f3n de herramientas que puedan ser \u00fatiles a los farmac\u00e9uticos y sirvan para facilitarles informaci\u00f3n t\u00e9cnica sobre estos productos, explic\u00f3 Anna Bach, Vocal de Alimentaci\u00f3n y Nutrici\u00f3n del COFB<\/strong><\/li>\n<\/ul>\n<p><strong>Barcelona, 10 de abril de 2015.- <\/strong>Los complementos alimenticios han experimentado un gran auge en su comercializaci\u00f3n, tanto en n\u00famero como en diversidad. Uno de los motivos que lo han causado es la creciente preocupaci\u00f3n de la poblaci\u00f3n por su salud, que cada vez m\u00e1s se interesa por mantener una nutrici\u00f3n \u00f3ptima. \u201cEstamos en la frontera entre medicamentos y alimentos, la legislaci\u00f3n es muy estricta en cuanto a qu\u00e9 propiedades podemos atribuir a un alimento\u201d, explic\u00f3 Andreu Palou, director del Laboratorio de Biolog\u00eda Molecular, Nutrici\u00f3n y Biotecnolog\u00eda de la Universitat de les Illes Balears y del centro de Investigaci\u00f3n Biom\u00e9dica en Red sobre Obesidad y Nutrici\u00f3n (CIBERobn) durante la mesa redonda \u201cHealth Claims en complementos alimenticios. \u00bfEn qu\u00e9 se sustentan?\u201d, celebrada en Infarma Barcelona 2015.<\/p>\n<p>\u201cLa normativa reconoce las propiedades beneficiosas de un alimento y su capacidad para prevenir o reducir el riesgo de padecer algunas enfermedades\u201d, explic\u00f3 Palou. En los \u00faltimos a\u00f1os ha habido diversos intentos de modificar la legislaci\u00f3n con el fin de hacer un uso m\u00e1s riguroso de las alegaciones de salud que estaban surgiendo en el mercado. \u201cLos complementos alimenticios deben estar sustentados por una evidencia cient\u00edfica. La EFSA (Agencia Europea de Seguridad Alimentaria) eval\u00faa sus efectos y es la encargada de aprobar si pueden atribuirse determinadas propiedades beneficiosas\u201d, indic\u00f3 Palou.<\/p>\n<p>De hecho, la EFSA sigue unos criterios estrictos a la hora de aprobar o no los Health Claims, puesto que no todos los alimentos tienen este atributo. Sin embargo, que un producto no est\u00e9 aprobado con una alegaci\u00f3n de salud no significa que no tenga evidencias de serlo. Es el caso de los probi\u00f3ticos, que no tienen un Health Claim pero s\u00ed que existen evidencias detr\u00e1s de ellos.<\/p>\n<p>Seg\u00fan explic\u00f3 Palou, en estos momentos existen 30 complementos alimenticios y 260 alegaciones de salud autorizadas, 2.020 se han rechazado y 2.151 est\u00e1n pendientes de validaci\u00f3n. Este tipo de nutrientes, indic\u00f3 Palou, est\u00e1n dirigidos a la poblaci\u00f3n sana.<\/p>\n<p>Victoria Castell, responsable del \u00c1rea de Planificaci\u00f3n y Auditoria de la Agencia Catalana de Seguridad Alimentaria (ACSA) del Departament de Salut de la Generalitat de Catalunya, mostr\u00f3 las principales caracter\u00edsticas que debe cumplir un alimento para ser autorizado.\u201dDebe quedar demostrado un efecto beneficioso de ese nutriente, debe estar presente en cantidad suficiente y en una forma asimilable por el organismo y en la cantidad suficiente para justificar el efecto beneficioso\u201d.<\/p>\n<p>Por otro lado, Castell advirti\u00f3 sobre los principios que deben inspirar las declaraciones. \u201cNo han de ser falsas o ambiguas, no deben provocar dudas sobre la seguridad de los alimentos, ni promover el consumo excesivo de este alimento y, en ning\u00fan caso, sugerir que una dieta equilibrada no es suficiente para aportar los nutrientes necesarios\u201d. Tambi\u00e9n record\u00f3 que la normativa debe establecer \u201cunos niveles m\u00e1ximos de las dosis que sirven para mejorar la salud o completar la alimentaci\u00f3n sin suponer un riesgo para la salud\u201d.<\/p>\n<p>Por su parte, Montserrat Rivero, directora general cient\u00edfica de Laboratorios Ordesa, explic\u00f3 c\u00f3mo la industria se est\u00e1 uniendo en consorcios de proyectos de investigaci\u00f3n facilitados por diversos programas convocados por los Ministerios de Industria CDTI y Econom\u00eda a trav\u00e9s de ayudas financieras para investigaciones precl\u00ednicas y cl\u00ednicas que validen los nuevos productos antes de salir al mercado. Es el caso de la plataforma Food for Life, que re\u00fane a empresas del sector alimentario con el objetivo de trabajar juntas en el desarrollo de alimentos saludables. \u201cLa investigaci\u00f3n es un camino muy largo y costoso que muchas empresas no pueden realizar si no se unen\u201d,  afirm\u00f3. Adem\u00e1s a\u00f1adi\u00f3 que la industria \u201cdebe invertir en I+D para innovar en productos que puedan ser validados cient\u00edficamente y establecer canales de di\u00e1logo\u201d.<\/p>\n<p>Otra de las iniciativas que explic\u00f3 Rivero es el proyecto INCOMES, que re\u00fane a 10 empresas y 27 centros de investigaci\u00f3n con el objetivo de elaborar una gu\u00eda de propiedades saludables de los alimentos.<\/p>\n<p><strong>Conocimiento y formaci\u00f3n al alcance de los farmac\u00e9uticos<\/strong><\/p>\n<p>\u201cLas instituciones deben colaborar en la formaci\u00f3n del farmac\u00e9utico\u201d, afirm\u00f3 la directora general cient\u00edfica de Laboratorios Ordesa. En esta l\u00ednea, Anna Bach, vocal de Alimentaci\u00f3n y Nutrici\u00f3n del COFB, explic\u00f3 una de las herramientas que se han creado para llevarlo a cabo. Se trata de una ficha t\u00e9cnica de ingredientes de complementos para poder recopilar informaci\u00f3n sobre estos productos. El objetivo es proporcionar al farmac\u00e9utico un criterio claro de los ingredientes de los complementos que suscitan controversia en el uso, as\u00ed como un canal de notificaci\u00f3n de alertas contrastado para los profesionales. \u201cEs importante que cuenten con el asesoramiento especializado de un profesional que garantice su calidad y la idoneidad de uso\u201d, se\u00f1al\u00f3 Anna Bach.<\/p>\n<p>La vocal del COFB manifest\u00f3 que las \u201dVocal\u00edas de los Colegios Oficiales de Farmac\u00e9uticos, as\u00ed como las Comisiones y consorcios, tienen una misi\u00f3n relevante en la resoluci\u00f3n de incertidumbres en el mercado de complementos alimenticios para facilitar al farmac\u00e9utico su asesoramiento en esta materia\u201d.<\/p>\n<p>Por su parte, Victoria Castell mostr\u00f3 el proyecto que la ACSA (Agencia Catalana de Seguridad Alimentaria) est\u00e1 desarrollando juntamente con el COFB, y que se basa en un dec\u00e1logo sobre los complementos alimenticios para el consumidor.<\/p>\n<p><strong>Acerca de Infarma<\/strong><\/p>\n<p>El XXVII Congreso y Sal\u00f3n Europeo de Farmacia INFARMA, punto de encuentro del sector farmac\u00e9utico, tuvo lugar del 24 al 26 de marzo en el recinto ferial de Gran Via de Barcelona, organizado por los Colegios de Farmac\u00e9uticos de Barcelona y Madrid con la colaboraci\u00f3n de Interalia. Durante tres d\u00edas m\u00e1s de 220 ponentes de \u00e1mbito nacional e internacional se han dado cita para hablar, en las 10 mesas de debate y m\u00e1s de 60 aulas activas, sobre los nuevos servicios que ofrecen las farmacias al paciente de forma creciente, as\u00ed como sobre la actualidad y las perspectivas del sector, bajo el lema escogido para esta edici\u00f3n: \u201cOrientados a la acci\u00f3n. Experiencias para mejorar la farmacia desde el presente\u201d.<\/p>\n<p><strong>INFARMA BARCELONA 2015 EN CIFRAS<\/strong><\/p>\n<p><strong>Programa <\/strong><\/p>\n<ul>\n<li>M\u00e1s de 60 aulas activas y 10 mesas redondas<\/li>\n<li>M\u00e1s de 220 ponentes<\/li>\n<\/ul>\n<p><strong>Visitantes, congresistas y expositores<\/strong><\/p>\n<ul>\n<li>M\u00e1s de 25.000 profesionales<\/li>\n<li>M\u00e1s de 2.500 congresistas<\/li>\n<li>328 laboratorios y empresas expositoras<\/li>\n<li>1.100 marcas<\/li>\n<\/ul>\n<p><strong>Para m\u00e1s informaci\u00f3n:<\/strong><br \/>Departamento de Comunicaci\u00f3n<br \/>Infarma 2015 www.infarma.es. Y tambi\u00e9n en Twitter.<br \/>Tel. 93 244 07 28 \/ 18<br \/>premsa@cofb.net<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0La EFSA es el organismo encargado de autorizar un Health Claim y validar sus propiedades beneficiosas seg\u00fan los resultados cient\u00edficos presentadosDesde el COF de Barcelona se est\u00e1 impulsando la creaci\u00f3n de herramientas que puedan ser \u00fatiles a los farmac\u00e9uticos y sirvan para facilitarles informaci\u00f3n t\u00e9cnica sobre estos productos, explic\u00f3 Anna Bach, Vocal de Alimentaci\u00f3n y Nutrici\u00f3n del COFBBarcelona, 10 de abril de 2015.- Los complementos alimenticios han experimentado un gran auge en su comercializaci\u00f3n, tanto en n\u00famero como en diversidad. Uno de los motivos que lo han causado es la creciente preocupaci\u00f3n de la poblaci\u00f3n por su salud, que cada vez m\u00e1s se interesa por mantener una nutrici\u00f3n \u00f3ptima. \u201cEstamos en la frontera entre medicamentos y alimentos, la legislaci\u00f3n es muy estricta en cuanto a qu\u00e9 propiedades podemos atribuir a un alimento\u201d, explic\u00f3 Andreu Palou, director del Laboratorio de Biolog\u00eda Molecular, Nutrici\u00f3n y Biotecnolog\u00eda de la Universitat de les Illes Balears y del centro de Investigaci\u00f3n Biom\u00e9dica en Red sobre Obesidad y Nutrici\u00f3n (CIBERobn) durante la mesa redonda \u201cHealth Claims en complementos alimenticios. \u00bfEn qu\u00e9 se sustentan?\u201d, celebrada en Infarma Barcelona 2015.\u201cLa normativa reconoce las propiedades beneficiosas de un alimento y su capacidad para prevenir o reducir el riesgo de padecer algunas enfermedades\u201d, explic\u00f3 Palou. En los \u00faltimos a\u00f1os ha habido diversos intentos de modificar la legislaci\u00f3n con el fin de hacer un uso m\u00e1s riguroso de las alegaciones de salud que estaban surgiendo en el mercado. \u201cLos complementos alimenticios deben estar sustentados por una evidencia cient\u00edfica. La EFSA (Agencia Europea de Seguridad Alimentaria) eval\u00faa sus efectos y es la encargada de aprobar si pueden atribuirse determinadas propiedades beneficiosas\u201d, indic\u00f3 Palou.De hecho, la EFSA sigue unos criterios estrictos a la hora de aprobar o no los Health Claims, puesto que no todos los alimentos tienen este atributo. Sin embargo, que un producto no est\u00e9 aprobado con una alegaci\u00f3n de salud no significa que no tenga evidencias de serlo. Es el caso de los probi\u00f3ticos, que no tienen un Health Claim pero s\u00ed que existen evidencias detr\u00e1s de ellos.Seg\u00fan explic\u00f3 Palou, en estos momentos existen 30 complementos alimenticios y 260 alegaciones de salud autorizadas, 2.020 se han rechazado y 2.151 est\u00e1n pendientes de validaci\u00f3n. Este tipo de nutrientes, indic\u00f3 Palou, est\u00e1n dirigidos a la poblaci\u00f3n sana.Victoria Castell, responsable del \u00c1rea de Planificaci\u00f3n y Auditoria de la Agencia Catalana de Seguridad Alimentaria (ACSA) del Departament de Salut de la Generalitat de Catalunya, mostr\u00f3 las principales caracter\u00edsticas que debe cumplir un alimento para ser autorizado.\u201dDebe quedar demostrado un efecto beneficioso de ese nutriente, debe estar presente en cantidad suficiente y en una forma asimilable por el organismo y en la cantidad suficiente para justificar el efecto beneficioso\u201d.Por otro lado, Castell advirti\u00f3 sobre los principios que deben inspirar las declaraciones. \u201cNo han de ser falsas o ambiguas, no deben provocar dudas sobre la seguridad de los alimentos, ni promover el consumo excesivo de este alimento y, en ning\u00fan caso, sugerir que una dieta equilibrada no es suficiente para aportar los nutrientes necesarios\u201d. Tambi\u00e9n record\u00f3 que la normativa debe establecer \u201cunos niveles m\u00e1ximos de las dosis que sirven para mejorar la salud o completar la alimentaci\u00f3n sin suponer un riesgo para la salud\u201d.Por su parte, Montserrat Rivero, directora general cient\u00edfica de Laboratorios Ordesa, explic\u00f3 c\u00f3mo la industria se est\u00e1 uniendo en consorcios de proyectos de investigaci\u00f3n facilitados por diversos programas convocados por los Ministerios de Industria CDTI y Econom\u00eda a trav\u00e9s de ayudas financieras para investigaciones precl\u00ednicas y cl\u00ednicas que validen los nuevos productos antes de salir al mercado. Es el caso de la plataforma Food for Life, que re\u00fane a empresas del sector alimentario con el objetivo de trabajar juntas en el desarrollo de alimentos saludables. \u201cLa investigaci\u00f3n es un camino muy largo y costoso que muchas empresas no pueden realizar si no se unen\u201d,  afirm\u00f3. Adem\u00e1s a\u00f1adi\u00f3 que la industria \u201cdebe invertir en I+D para innovar en productos que puedan ser validados cient\u00edficamente y establecer canales de di\u00e1logo\u201d.Otra de las iniciativas que explic\u00f3 Rivero es el proyecto INCOMES, que re\u00fane a 10 empresas y 27 centros de investigaci\u00f3n con el objetivo de elaborar una gu\u00eda de propiedades saludables de los alimentos.Conocimiento y formaci\u00f3n al alcance de los farmac\u00e9uticos\u201cLas instituciones deben colaborar en la formaci\u00f3n del farmac\u00e9utico\u201d, afirm\u00f3 la directora general cient\u00edfica de Laboratorios Ordesa. En esta l\u00ednea, Anna Bach, vocal de Alimentaci\u00f3n y Nutrici\u00f3n del COFB, explic\u00f3 una de las herramientas que se han creado para llevarlo a cabo. Se trata de una ficha t\u00e9cnica de ingredientes de complementos para poder recopilar informaci\u00f3n sobre estos productos. El objetivo es proporcionar al farmac\u00e9utico un criterio claro de los ingredientes de los complementos que suscitan controversia en el uso, as\u00ed como un canal de notificaci\u00f3n de alertas contrastado para los profesionales. \u201cEs importante que cuenten con el asesoramiento especializado de un profesional que garantice su calidad y la idoneidad de uso\u201d, se\u00f1al\u00f3 Anna Bach.La vocal del COFB manifest\u00f3 que las \u201dVocal\u00edas de los Colegios Oficiales de Farmac\u00e9uticos, as\u00ed como las Comisiones y consorcios, tienen una misi\u00f3n relevante en la resoluci\u00f3n de incertidumbres en el mercado de complementos alimenticios para facilitar al farmac\u00e9utico su asesoramiento en esta materia\u201d.Por su parte, Victoria Castell mostr\u00f3 el proyecto que la ACSA (Agencia Catalana de Seguridad Alimentaria) est\u00e1 desarrollando juntamente con el COFB, y que se basa en un dec\u00e1logo sobre los complementos alimenticios para el consumidor.Acerca de InfarmaEl XXVII Congreso y Sal\u00f3n Europeo de Farmacia INFARMA, punto de encuentro del sector farmac\u00e9utico, tuvo lugar del 24 al 26 de marzo en el recinto ferial de Gran Via de Barcelona, organizado por los Colegios de Farmac\u00e9uticos de Barcelona y Madrid con la colaboraci\u00f3n de Interalia. Durante tres d\u00edas m\u00e1s de 220 ponentes de \u00e1mbito nacional e internacional se han dado cita para hablar, en las 10 mesas de debate y m\u00e1s de 60 aulas activas, sobre los nuevos servicios que ofrecen las farmacias al paciente de forma creciente, as\u00ed como sobre la actualidad y las perspectivas del sector, bajo el lema escogido para esta edici\u00f3n: \u201cOrientados a la acci\u00f3n. Experiencias para mejorar la farmacia desde el presente\u201d.INFARMA BARCELONA 2015 EN CIFRASPrograma M\u00e1s de 60 aulas activas y 10 mesas redondasM\u00e1s de 220 ponentesVisitantes, congresistas y expositoresM\u00e1s de 25.000 profesionalesM\u00e1s de 2.500 congresistas328 laboratorios y empresas expositoras1.100 marcasPara m\u00e1s informaci\u00f3n:Departamento de Comunicaci\u00f3nInfarma 2015 www.infarma.es. Y tambi\u00e9n en Twitter.Tel. 93 244 07 28 \/ 18premsa@cofb.net\u00a0\u00a0\u00a0COFB.ORG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 La EFSA es el organismo encargado de autorizar un Health Claim y validar sus propiedades beneficiosas seg\u00fan los resultados cient\u00edficos presentados Desde el COF de Barcelona se est\u00e1 impulsando la creaci\u00f3n de herramientas que puedan ser \u00fatiles a los farmac\u00e9uticos y sirvan para facilitarles informaci\u00f3n t\u00e9cnica sobre estos productos, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1060,1066],"tags":[],"class_list":["post-77460","post","type-post","status-publish","format-standard","hentry","category-notes-premsa","category-sense-categoria-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Los complementos alimenticios deben estar sustentados por la evidencia cient\u00edfica&quot; - Col\u00b7legi de Farmac\u00e8utics de Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Los complementos alimenticios deben estar sustentados por la evidencia cient\u00edfica&quot; - Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"og:description\" content=\"\u00a0 La EFSA es el organismo encargado de autorizar un Health Claim y validar sus propiedades beneficiosas seg\u00fan los resultados cient\u00edficos presentados Desde el COF de Barcelona se est\u00e1 impulsando la creaci\u00f3n de herramientas que puedan ser \u00fatiles a los farmac\u00e9uticos y sirvan para facilitarles informaci\u00f3n t\u00e9cnica sobre estos productos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-10T15:30:00+00:00\" \/>\n<meta name=\"author\" content=\"wpAdminCofbOrg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:site\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpAdminCofbOrg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/\"},\"author\":{\"name\":\"wpAdminCofbOrg\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\"},\"headline\":\"&#8220;Los complementos alimenticios deben estar sustentados por la evidencia cient\u00edfica&#8221;\",\"datePublished\":\"2015-04-10T15:30:00+00:00\",\"dateModified\":\"2015-04-10T15:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/\"},\"wordCount\":2304,\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"articleSection\":[\"Notes de premsa\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/\",\"url\":\"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/\",\"name\":\"\\\"Los complementos alimenticios deben estar sustentados por la evidencia cient\u00edfica\\\" - Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.cofb.org\/#website\"},\"datePublished\":\"2015-04-10T15:30:00+00:00\",\"dateModified\":\"2015-04-10T15:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.cofb.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Los complementos alimenticios deben estar sustentados por la evidencia cient\u00edfica&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cofb.org\/#website\",\"url\":\"https:\/\/www.cofb.org\/\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cofb.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cofb.org\/#organization\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"url\":\"https:\/\/www.cofb.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"contentUrl\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"width\":500,\"height\":105,\"caption\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\"},\"image\":{\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\",\"https:\/\/twitter.com\/farmaceuticsbcn\",\"https:\/\/www.instagram.com\/farmaceuticsbcn\/\",\"https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\",\"name\":\"wpAdminCofbOrg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"caption\":\"wpAdminCofbOrg\"},\"sameAs\":[\"http:\/\/192.168.64.122\/wordpress\"],\"url\":\"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Los complementos alimenticios deben estar sustentados por la evidencia cient\u00edfica\" - Col\u00b7legi de Farmac\u00e8utics de Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/","og_locale":"ca_ES","og_type":"article","og_title":"\"Los complementos alimenticios deben estar sustentados por la evidencia cient\u00edfica\" - Col\u00b7legi de Farmac\u00e8utics de Barcelona","og_description":"\u00a0 La EFSA es el organismo encargado de autorizar un Health Claim y validar sus propiedades beneficiosas seg\u00fan los resultados cient\u00edficos presentados Desde el COF de Barcelona se est\u00e1 impulsando la creaci\u00f3n de herramientas que puedan ser \u00fatiles a los farmac\u00e9uticos y sirvan para facilitarles informaci\u00f3n t\u00e9cnica sobre estos productos, [&hellip;]","og_url":"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/","og_site_name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","article_publisher":"https:\/\/www.facebook.com\/farmaceuticsbcn\/","article_published_time":"2015-04-10T15:30:00+00:00","author":"wpAdminCofbOrg","twitter_card":"summary_large_image","twitter_creator":"@farmaceuticsbcn","twitter_site":"@farmaceuticsbcn","twitter_misc":{"Escrit per":"wpAdminCofbOrg","Temps estimat de lectura":"11 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/#article","isPartOf":{"@id":"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/"},"author":{"name":"wpAdminCofbOrg","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb"},"headline":"&#8220;Los complementos alimenticios deben estar sustentados por la evidencia cient\u00edfica&#8221;","datePublished":"2015-04-10T15:30:00+00:00","dateModified":"2015-04-10T15:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/"},"wordCount":2304,"publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"articleSection":["Notes de premsa"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/","url":"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/","name":"\"Los complementos alimenticios deben estar sustentados por la evidencia cient\u00edfica\" - Col\u00b7legi de Farmac\u00e8utics de Barcelona","isPartOf":{"@id":"https:\/\/www.cofb.org\/#website"},"datePublished":"2015-04-10T15:30:00+00:00","dateModified":"2015-04-10T15:30:00+00:00","breadcrumb":{"@id":"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/novaorg.cofb.net\/2015\/04\/10\/los-complementos-alimenticios-deben-estar-sustentados-por-la-evidencia-cientifica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cofb.org\/"},{"@type":"ListItem","position":2,"name":"&#8220;Los complementos alimenticios deben estar sustentados por la evidencia cient\u00edfica&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.cofb.org\/#website","url":"https:\/\/www.cofb.org\/","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","description":"","publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cofb.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.cofb.org\/#organization","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","url":"https:\/\/www.cofb.org\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","contentUrl":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","width":500,"height":105,"caption":"Col\u00b7legi de Farmac\u00e8utics de Barcelona"},"image":{"@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/farmaceuticsbcn\/","https:\/\/twitter.com\/farmaceuticsbcn","https:\/\/www.instagram.com\/farmaceuticsbcn\/","https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/"]},{"@type":"Person","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb","name":"wpAdminCofbOrg","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","caption":"wpAdminCofbOrg"},"sameAs":["http:\/\/192.168.64.122\/wordpress"],"url":"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"wpAdminCofbOrg","author_link":"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00a0 La EFSA es el organismo encargado de autorizar un Health Claim y validar sus propiedades beneficiosas seg\u00fan los resultados cient\u00edficos presentados Desde el COF de Barcelona se est\u00e1 impulsando la creaci\u00f3n de herramientas que puedan ser \u00fatiles a los farmac\u00e9uticos y sirvan para facilitarles informaci\u00f3n t\u00e9cnica sobre estos productos, [&hellip;]","_links":{"self":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts\/77460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/comments?post=77460"}],"version-history":[{"count":0,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts\/77460\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/media?parent=77460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/categories?post=77460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/tags?post=77460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}