{"id":77426,"date":"2015-12-09T17:47:00","date_gmt":"2015-12-09T17:47:00","guid":{"rendered":"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/"},"modified":"2015-12-09T17:47:00","modified_gmt":"2015-12-09T17:47:00","slug":"una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis","status":"publish","type":"post","link":"https:\/\/www.cofb.org\/ca\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/","title":{"rendered":"Una formaci\u00f3 d&#8217;\u00c0gora Sanit\u00e0ria busca ajudar a reduir l&#8217;abandonament preco\u00e7 de la lact\u00e0ncia materna a causa del dolor i la mastitis"},"content":{"rendered":"<p>\u00a0<\/p>\n<ul>\n<li><strong>S&#8217;emmarca en un nou format anomenat \u00c0gora express, on la formaci\u00f3, de no m\u00e9s d&#8217;una hora de durada, respon a necessitats concretes manifestades per part dels alumnes <\/strong><\/li>\n<li><strong>Una bona recomanaci\u00f3 farmac\u00e8utica pot ajudar a les mares a aconseguir una lact\u00e0ncia sense dolor i contribuir aix\u00ed al fet que, en la mesura del possible, el beb\u00e8 s&#8217;alimenti de llet materna el temps recomanat <\/strong><br \/>\u00a0<\/li>\n<\/ul>\n<p><i>Barcelona, 9 de desembre de 2015. <\/i><span>En nombrosos estudis s&#8217;ha demostrat la import\u00e0ncia de la lact\u00e0ncia materna per al beb\u00e8 que, entre altres beneficis, fomenta el seu desenvolupament sensorial i cognitiu, i el protegeix de les malalties infeccioses i cr\u00f2niques, tal com apunta l&#8217;OMS. <b>Per donar m\u00e9s eines als farmac\u00e8utics que ajudin a evitar l&#8217;abandonament preco\u00e7 de la lact\u00e0ncia materna a causa d&#8217;afeccions com la mastitis, \u00c0gora Sanit\u00e0ria,<\/b> el portal de formaci\u00f3 online dels Col\u00b7legis de Farmac\u00e8utics de Barcelona i Madrid, <b>ha posat en marxa el curs \u201cLact\u00e0ncia sense dolor: mastitis i probi\u00f2tics\u201d<\/b>. Per accedir a les <a href=\"http:\/\/www.agorasanitaria.com\/web\/guest\/oferta-formativa?p_p_id=portletllistatactivitats_WAR_portletllistatactivitats_INSTANCE_O4dm&amp;p_p_lifecycle=0&amp;p_p_state=normal&amp;p_p_mode=view&amp;p_p_col_id=column-1&amp;p_p_col_pos=2&amp;p_p_col_count=3&amp;_portletllistatactivitats_WAR_portletllistatactivitats_INSTANCE_O4dm_strutsAction=%2Fview%2Fdetall&amp;_portletllistatactivitats_WAR_portletllistatactivitats_INSTANCE_O4dm_id=231\">inscripcions<\/a>, obertes fins al 18 de novembre del 2016, es pot fer a trav\u00e9s de la web d&#8217;\u00c0gora Sanit\u00e0ria.<span class=\"apple-converted-space\">\u00a0<\/span><\/span><\/p>\n<p class=\"MsoNormal\"><b><u><span>Probi\u00f2tics, una nova eina en el camp de les mastitis<\/p>\n<p><\/span><\/u><\/b><\/p>\n<p class=\"MsoNormal\"><span>Amb aquesta formaci\u00f3, que compta amb el <b>patrocini d\u2019Angelini Farmac\u00e9utica,<\/b> \u00c0gora persegueix proporcionar<b> m\u00e9s eines als farmac\u00e8utics per abordar les consultes sobre mastitis, <\/b>una de les m\u00e9s habituals al postpart, i realitzar, d&#8217;aquesta manera, una <b>correcta recomanaci\u00f3 farmac\u00e8utica, comptant amb el recurs dels probi\u00f2tics.<\/b> Aquests microorganismes vius, en ingerir-se en quantitats adequades, ajuden a equilibrar la flora bacteriana de la gl\u00e0ndula mam\u00e0ria i a restablir l&#8217;equilibri de la flora mam\u00e0ria.<span class=\"apple-converted-space\">\u00a0<\/p>\n<p><\/span><\/span><\/p>\n<p class=\"MsoNormal\"><span>La formaci\u00f3 \u2013elaborada per un equip multidisciplinari que compta amb la participaci\u00f3 d&#8217;una matrona i una farmac\u00e8utica comunit\u00e0ria\u2013 se centra tamb\u00e9 en la correcta aplicaci\u00f3 de les recomanacions d&#8217;actuaci\u00f3 farmac\u00e8utica davant una consulta per dolor en el pit durant la lact\u00e0ncia, com acompanyar la indicaci\u00f3 farmac\u00e8utica d&#8217;informaci\u00f3 personalitzada i quines mesures higi\u00e8nic-diet\u00e8tiques proporcionar per al tractament i la prevenci\u00f3 de les mastitis.<\/span><\/p>\n<p><b><u><span>\u00c0gora express, nou format engegat al portal<span class=\"apple-converted-space\">\u00a0<\/p>\n<p><\/span><\/span><\/u><\/b><\/p>\n<p class=\"MsoNormal\"><span>Aquest curs sobre mastitis s&#8217;emmarca en el nou format que s&#8217;ha engegat anomenat <b>\u00c0gora Express.<\/b> Gr\u00e0cies a aquest sistema, s&#8217;ofereixen c<b>ursos de temes espec\u00edfics de no m\u00e9s d&#8217;una hora durada, <\/b>que responen a actualitzacions puntuals o necessitats concretes manifestades per part dels alumnes. Al seu torn, tamb\u00e9 es proporciona una <b>formaci\u00f3 r\u00e0pida i efectiva en q\u00fcestions que el farmac\u00e8utic necessita en el seu dia a dia,<\/b> i l&#8217;eix d&#8217;aprenentatge es basa en l&#8217;enfocament pr\u00e0ctic dels continguts i la col\u00b7laboraci\u00f3 i intercanvi d&#8217;experi\u00e8ncies entre els participants.<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>Per a m\u00e9s informaci\u00f3:<\/span><\/strong><span><br \/>Departament de Comunicaci\u00f3 del Col\u00b7legi de Farmac\u00e8utics de Barcelona (COFB)<br \/>premsa@cofb.net \/ Tels. 93 244 07 28 \/ 18<\/p>\n<p><\/span><\/p>\n<p>\u00a0S&#8217;emmarca en un nou format anomenat \u00c0gora express, on la formaci\u00f3, de no m\u00e9s d&#8217;una hora de durada, respon a necessitats concretes manifestades per part dels alumnes Una bona recomanaci\u00f3 farmac\u00e8utica pot ajudar a les mares a aconseguir una lact\u00e0ncia sense dolor i contribuir aix\u00ed al fet que, en la mesura del possible, el beb\u00e8 s&#8217;alimenti de llet materna el temps recomanat \u00a0Barcelona, 9 de desembre de 2015. En nombrosos estudis s&#8217;ha demostrat la import\u00e0ncia de la lact\u00e0ncia materna per al beb\u00e8 que, entre altres beneficis, fomenta el seu desenvolupament sensorial i cognitiu, i el protegeix de les malalties infeccioses i cr\u00f2niques, tal com apunta l&#8217;OMS. Per donar m\u00e9s eines als farmac\u00e8utics que ajudin a evitar l&#8217;abandonament preco\u00e7 de la lact\u00e0ncia materna a causa d&#8217;afeccions com la mastitis, \u00c0gora Sanit\u00e0ria, el portal de formaci\u00f3 online dels Col\u00b7legis de Farmac\u00e8utics de Barcelona i Madrid, ha posat en marxa el curs \u201cLact\u00e0ncia sense dolor: mastitis i probi\u00f2tics\u201d. Per accedir a les inscripcions, obertes fins al 18 de novembre del 2016, es pot fer a trav\u00e9s de la web d&#8217;\u00c0gora Sanit\u00e0ria.\u00a0Probi\u00f2tics, una nova eina en el camp de les mastitis  Amb aquesta formaci\u00f3, que compta amb el patrocini d\u2019Angelini Farmac\u00e9utica, \u00c0gora persegueix proporcionar m\u00e9s eines als farmac\u00e8utics per abordar les consultes sobre mastitis, una de les m\u00e9s habituals al postpart, i realitzar, d&#8217;aquesta manera, una correcta recomanaci\u00f3 farmac\u00e8utica, comptant amb el recurs dels probi\u00f2tics. Aquests microorganismes vius, en ingerir-se en quantitats adequades, ajuden a equilibrar la flora bacteriana de la gl\u00e0ndula mam\u00e0ria i a restablir l&#8217;equilibri de la flora mam\u00e0ria.\u00a0  La formaci\u00f3 \u2013elaborada per un equip multidisciplinari que compta amb la participaci\u00f3 d&#8217;una matrona i una farmac\u00e8utica comunit\u00e0ria\u2013 se centra tamb\u00e9 en la correcta aplicaci\u00f3 de les recomanacions d&#8217;actuaci\u00f3 farmac\u00e8utica davant una consulta per dolor en el pit durant la lact\u00e0ncia, com acompanyar la indicaci\u00f3 farmac\u00e8utica d&#8217;informaci\u00f3 personalitzada i quines mesures higi\u00e8nic-diet\u00e8tiques proporcionar per al tractament i la prevenci\u00f3 de les mastitis.\u00c0gora express, nou format engegat al portal\u00a0    Aquest curs sobre mastitis s&#8217;emmarca en el nou format que s&#8217;ha engegat anomenat \u00c0gora Express. Gr\u00e0cies a aquest sistema, s&#8217;ofereixen cursos de temes espec\u00edfics de no m\u00e9s d&#8217;una hora durada, que responen a actualitzacions puntuals o necessitats concretes manifestades per part dels alumnes. Al seu torn, tamb\u00e9 es proporciona una formaci\u00f3 r\u00e0pida i efectiva en q\u00fcestions que el farmac\u00e8utic necessita en el seu dia a dia, i l&#8217;eix d&#8217;aprenentatge es basa en l&#8217;enfocament pr\u00e0ctic dels continguts i la col\u00b7laboraci\u00f3 i intercanvi d&#8217;experi\u00e8ncies entre els participants.Per a m\u00e9s informaci\u00f3:Departament de Comunicaci\u00f3 del Col\u00b7legi de Farmac\u00e8utics de Barcelona (COFB)premsa@cofb.net \/ Tels. 93 244 07 28 \/ 18\u00a0\u00a0COFB.ORG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 S&#8217;emmarca en un nou format anomenat \u00c0gora express, on la formaci\u00f3, de no m\u00e9s d&#8217;una hora de durada, respon a necessitats concretes manifestades per part dels alumnes Una bona recomanaci\u00f3 farmac\u00e8utica pot ajudar a les mares a aconseguir una lact\u00e0ncia sense dolor i contribuir aix\u00ed al fet que, en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1060,1066],"tags":[],"class_list":["post-77426","post","type-post","status-publish","format-standard","hentry","category-notes-premsa","category-sense-categoria-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una formaci\u00f3 d&#039;\u00c0gora Sanit\u00e0ria busca ajudar a reduir l&#039;abandonament preco\u00e7 de la lact\u00e0ncia materna a causa del dolor i la mastitis - Col\u00b7legi de Farmac\u00e8utics de Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una formaci\u00f3 d&#039;\u00c0gora Sanit\u00e0ria busca ajudar a reduir l&#039;abandonament preco\u00e7 de la lact\u00e0ncia materna a causa del dolor i la mastitis - Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"og:description\" content=\"\u00a0 S&#8217;emmarca en un nou format anomenat \u00c0gora express, on la formaci\u00f3, de no m\u00e9s d&#8217;una hora de durada, respon a necessitats concretes manifestades per part dels alumnes Una bona recomanaci\u00f3 farmac\u00e8utica pot ajudar a les mares a aconseguir una lact\u00e0ncia sense dolor i contribuir aix\u00ed al fet que, en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-09T17:47:00+00:00\" \/>\n<meta name=\"author\" content=\"wpAdminCofbOrg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:site\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpAdminCofbOrg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/\"},\"author\":{\"name\":\"wpAdminCofbOrg\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\"},\"headline\":\"Una formaci\u00f3 d&#8217;\u00c0gora Sanit\u00e0ria busca ajudar a reduir l&#8217;abandonament preco\u00e7 de la lact\u00e0ncia materna a causa del dolor i la mastitis\",\"datePublished\":\"2015-12-09T17:47:00+00:00\",\"dateModified\":\"2015-12-09T17:47:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/\"},\"wordCount\":1013,\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"articleSection\":[\"Notes de premsa\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/\",\"url\":\"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/\",\"name\":\"Una formaci\u00f3 d'\u00c0gora Sanit\u00e0ria busca ajudar a reduir l'abandonament preco\u00e7 de la lact\u00e0ncia materna a causa del dolor i la mastitis - Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.cofb.org\/#website\"},\"datePublished\":\"2015-12-09T17:47:00+00:00\",\"dateModified\":\"2015-12-09T17:47:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/novaorg.cofb.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una formaci\u00f3 d&#8217;\u00c0gora Sanit\u00e0ria busca ajudar a reduir l&#8217;abandonament preco\u00e7 de la lact\u00e0ncia materna a causa del dolor i la mastitis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cofb.org\/#website\",\"url\":\"https:\/\/www.cofb.org\/\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cofb.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cofb.org\/#organization\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"url\":\"https:\/\/www.cofb.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"contentUrl\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"width\":500,\"height\":105,\"caption\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\"},\"image\":{\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\",\"https:\/\/twitter.com\/farmaceuticsbcn\",\"https:\/\/www.instagram.com\/farmaceuticsbcn\/\",\"https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\",\"name\":\"wpAdminCofbOrg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"caption\":\"wpAdminCofbOrg\"},\"sameAs\":[\"http:\/\/192.168.64.122\/wordpress\"],\"url\":\"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una formaci\u00f3 d'\u00c0gora Sanit\u00e0ria busca ajudar a reduir l'abandonament preco\u00e7 de la lact\u00e0ncia materna a causa del dolor i la mastitis - Col\u00b7legi de Farmac\u00e8utics de Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/","og_locale":"ca_ES","og_type":"article","og_title":"Una formaci\u00f3 d'\u00c0gora Sanit\u00e0ria busca ajudar a reduir l'abandonament preco\u00e7 de la lact\u00e0ncia materna a causa del dolor i la mastitis - Col\u00b7legi de Farmac\u00e8utics de Barcelona","og_description":"\u00a0 S&#8217;emmarca en un nou format anomenat \u00c0gora express, on la formaci\u00f3, de no m\u00e9s d&#8217;una hora de durada, respon a necessitats concretes manifestades per part dels alumnes Una bona recomanaci\u00f3 farmac\u00e8utica pot ajudar a les mares a aconseguir una lact\u00e0ncia sense dolor i contribuir aix\u00ed al fet que, en [&hellip;]","og_url":"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/","og_site_name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","article_publisher":"https:\/\/www.facebook.com\/farmaceuticsbcn\/","article_published_time":"2015-12-09T17:47:00+00:00","author":"wpAdminCofbOrg","twitter_card":"summary_large_image","twitter_creator":"@farmaceuticsbcn","twitter_site":"@farmaceuticsbcn","twitter_misc":{"Escrit per":"wpAdminCofbOrg","Temps estimat de lectura":"5 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/#article","isPartOf":{"@id":"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/"},"author":{"name":"wpAdminCofbOrg","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb"},"headline":"Una formaci\u00f3 d&#8217;\u00c0gora Sanit\u00e0ria busca ajudar a reduir l&#8217;abandonament preco\u00e7 de la lact\u00e0ncia materna a causa del dolor i la mastitis","datePublished":"2015-12-09T17:47:00+00:00","dateModified":"2015-12-09T17:47:00+00:00","mainEntityOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/"},"wordCount":1013,"publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"articleSection":["Notes de premsa"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/","url":"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/","name":"Una formaci\u00f3 d'\u00c0gora Sanit\u00e0ria busca ajudar a reduir l'abandonament preco\u00e7 de la lact\u00e0ncia materna a causa del dolor i la mastitis - Col\u00b7legi de Farmac\u00e8utics de Barcelona","isPartOf":{"@id":"https:\/\/www.cofb.org\/#website"},"datePublished":"2015-12-09T17:47:00+00:00","dateModified":"2015-12-09T17:47:00+00:00","breadcrumb":{"@id":"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/novaorg.cofb.net\/2015\/12\/09\/una-formacio-dagora-sanitaria-busca-ajudar-a-reduir-labandonament-precoc-de-la-lactancia-materna-a-causa-del-dolor-i-la-mastitis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/novaorg.cofb.net\/"},{"@type":"ListItem","position":2,"name":"Una formaci\u00f3 d&#8217;\u00c0gora Sanit\u00e0ria busca ajudar a reduir l&#8217;abandonament preco\u00e7 de la lact\u00e0ncia materna a causa del dolor i la mastitis"}]},{"@type":"WebSite","@id":"https:\/\/www.cofb.org\/#website","url":"https:\/\/www.cofb.org\/","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","description":"","publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cofb.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.cofb.org\/#organization","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","url":"https:\/\/www.cofb.org\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","contentUrl":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","width":500,"height":105,"caption":"Col\u00b7legi de Farmac\u00e8utics de Barcelona"},"image":{"@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/farmaceuticsbcn\/","https:\/\/twitter.com\/farmaceuticsbcn","https:\/\/www.instagram.com\/farmaceuticsbcn\/","https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/"]},{"@type":"Person","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb","name":"wpAdminCofbOrg","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","caption":"wpAdminCofbOrg"},"sameAs":["http:\/\/192.168.64.122\/wordpress"],"url":"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"wpAdminCofbOrg","author_link":"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00a0 S&#8217;emmarca en un nou format anomenat \u00c0gora express, on la formaci\u00f3, de no m\u00e9s d&#8217;una hora de durada, respon a necessitats concretes manifestades per part dels alumnes Una bona recomanaci\u00f3 farmac\u00e8utica pot ajudar a les mares a aconseguir una lact\u00e0ncia sense dolor i contribuir aix\u00ed al fet que, en [&hellip;]","_links":{"self":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts\/77426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/comments?post=77426"}],"version-history":[{"count":0,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts\/77426\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/media?parent=77426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/categories?post=77426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/tags?post=77426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}