{"id":68798,"date":"2013-09-13T10:34:52","date_gmt":"2013-09-13T09:34:52","guid":{"rendered":"http:\/\/blog.cofb.cat\/?p=2932"},"modified":"2013-09-13T10:34:52","modified_gmt":"2013-09-13T09:34:52","slug":"motxilles-escolars-millor-la-desquena-que-la-de-rodes","status":"publish","type":"post","link":"https:\/\/www.cofb.org\/ca\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/","title":{"rendered":"Motxilles escolars: millor la d&#8217;esquena que la de rodes"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignright  wp-image-2940\" title=\"Foto: Dreamstime.com\" alt=\"maleta\" src=\"http:\/\/blog.cofb.cat\/wp-content\/uploads\/2013\/09\/maleta1.jpg\" width=\"180\" height=\"232\" \/>La tornada a l\u2019escola ja ha arribat i aix\u00f2 suposa per als nens portar una motxilla plena de llibres, llibretes, carpetes, material escolar etc. una c\u00e0rrega de vegades excessiva que pot generar problemes d\u2019esquena.<\/p>\n<p>Segons estudis realitzats, <b>s\u2019aconsella m\u00e9s l\u2019\u00fas de la motxilla d\u2019esquena que el de la motxilla de rodes,<\/b> perqu\u00e8 es considera que la for\u00e7a que fa el nen per estirar la motxilla de rodes no \u00e9s uniforme, sin\u00f3 que carrega m\u00e9s d\u2019un costat que d\u2019un altre.<\/p>\n<p>Ara b\u00e9, per a un \u00fas adequat,\u00a0<strong>el pes de la motxilla no hauria de sobrepassar el 10% del pes del nen<\/strong>, hauria d&#8217;estar\u00a0<strong>situada a la zona lumbar o entre els malucs<\/strong>\u00a0(i no als om\u00f2plats), i\u00a0<strong>s&#8217;hauria de poder graduar<\/strong>\u00a0segons l&#8217;al\u00e7ada del nen.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #888888;\"><strong>Factors que afavoreixen l\u2019aparici\u00f3 del mal d\u2019esquena:<\/strong><\/span><\/p>\n<ul>\n<li><b>Exc\u00e9s de c\u00e0rrega<\/b>, causat pel transport d\u2019un exc\u00e9s de material escolar i llibres.<\/li>\n<li><b>Sedentarisme<\/b>, ja que dificulta el desenvolupament ossi normal de la columna vertebral i comporta una p\u00e8rdua de la resist\u00e8ncia muscular.<\/li>\n<li><b>Mobiliari escolar inadequat<\/b>, moltes vegades no est\u00e0 adaptat a les necessitats del nen. Aix\u00f2 pot fer que es cre\u00efn uns h\u00e0bits posturals incorrectes.<\/li>\n<\/ul>\n<p>Aquest i altres temes els podr\u00e0s trobar al web del Col\u00b7legi\u00a0<span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.farmaceuticonline.com\/ca\/familia\/517-mochilas-escolares\"><b>Farmaceuticonline.<\/b><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tornada a l\u2019escola ja ha arribat i aix\u00f2 suposa per als nens portar una motxilla plena de llibres, llibretes, carpetes, material escolar etc. una c\u00e0rrega de vegades excessiva que pot generar problemes d\u2019esquena. Segons estudis realitzats, s\u2019aconsella m\u00e9s l\u2019\u00fas de la motxilla d\u2019esquena que el de la motxilla de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[47],"tags":[789],"class_list":["post-68798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recomanacions-del-farmaceutic","tag-recomanacions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Motxilles escolars: millor la d&#039;esquena que la de rodes - Col\u00b7legi de Farmac\u00e8utics de Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motxilles escolars: millor la d&#039;esquena que la de rodes - Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"og:description\" content=\"La tornada a l\u2019escola ja ha arribat i aix\u00f2 suposa per als nens portar una motxilla plena de llibres, llibretes, carpetes, material escolar etc. una c\u00e0rrega de vegades excessiva que pot generar problemes d\u2019esquena. Segons estudis realitzats, s\u2019aconsella m\u00e9s l\u2019\u00fas de la motxilla d\u2019esquena que el de la motxilla de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/\" \/>\n<meta property=\"og:site_name\" content=\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-13T09:34:52+00:00\" \/>\n<meta name=\"author\" content=\"wpAdminCofbOrg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:site\" content=\"@farmaceuticsbcn\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpAdminCofbOrg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/\"},\"author\":{\"name\":\"wpAdminCofbOrg\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\"},\"headline\":\"Motxilles escolars: millor la d&#8217;esquena que la de rodes\",\"datePublished\":\"2013-09-13T09:34:52+00:00\",\"dateModified\":\"2013-09-13T09:34:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/\"},\"wordCount\":238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Recomanacions\"],\"articleSection\":[\"Recomanacions del farmac\u00e8utic\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/\",\"url\":\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/\",\"name\":\"Motxilles escolars: millor la d'esquena que la de rodes - Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.cofb.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2013-09-13T09:34:52+00:00\",\"dateModified\":\"2013-09-13T09:34:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.cofb.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Motxilles escolars: millor la d&#8217;esquena que la de rodes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cofb.org\/#website\",\"url\":\"https:\/\/www.cofb.org\/\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cofb.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cofb.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cofb.org\/#organization\",\"name\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\",\"url\":\"https:\/\/www.cofb.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"contentUrl\":\"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png\",\"width\":500,\"height\":105,\"caption\":\"Col\u00b7legi de Farmac\u00e8utics de Barcelona\"},\"image\":{\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/farmaceuticsbcn\/\",\"https:\/\/twitter.com\/farmaceuticsbcn\",\"https:\/\/www.instagram.com\/farmaceuticsbcn\/\",\"https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb\",\"name\":\"wpAdminCofbOrg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.cofb.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g\",\"caption\":\"wpAdminCofbOrg\"},\"sameAs\":[\"http:\/\/192.168.64.122\/wordpress\"],\"url\":\"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motxilles escolars: millor la d'esquena que la de rodes - Col\u00b7legi de Farmac\u00e8utics de Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/","og_locale":"ca_ES","og_type":"article","og_title":"Motxilles escolars: millor la d'esquena que la de rodes - Col\u00b7legi de Farmac\u00e8utics de Barcelona","og_description":"La tornada a l\u2019escola ja ha arribat i aix\u00f2 suposa per als nens portar una motxilla plena de llibres, llibretes, carpetes, material escolar etc. una c\u00e0rrega de vegades excessiva que pot generar problemes d\u2019esquena. Segons estudis realitzats, s\u2019aconsella m\u00e9s l\u2019\u00fas de la motxilla d\u2019esquena que el de la motxilla de [&hellip;]","og_url":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/","og_site_name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","article_publisher":"https:\/\/www.facebook.com\/farmaceuticsbcn\/","article_published_time":"2013-09-13T09:34:52+00:00","author":"wpAdminCofbOrg","twitter_card":"summary_large_image","twitter_creator":"@farmaceuticsbcn","twitter_site":"@farmaceuticsbcn","twitter_misc":{"Escrit per":"wpAdminCofbOrg","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#article","isPartOf":{"@id":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/"},"author":{"name":"wpAdminCofbOrg","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb"},"headline":"Motxilles escolars: millor la d&#8217;esquena que la de rodes","datePublished":"2013-09-13T09:34:52+00:00","dateModified":"2013-09-13T09:34:52+00:00","mainEntityOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/"},"wordCount":238,"commentCount":0,"publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"image":{"@id":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#primaryimage"},"thumbnailUrl":"","keywords":["Recomanacions"],"articleSection":["Recomanacions del farmac\u00e8utic"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/","url":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/","name":"Motxilles escolars: millor la d'esquena que la de rodes - Col\u00b7legi de Farmac\u00e8utics de Barcelona","isPartOf":{"@id":"https:\/\/www.cofb.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#primaryimage"},"image":{"@id":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#primaryimage"},"thumbnailUrl":"","datePublished":"2013-09-13T09:34:52+00:00","dateModified":"2013-09-13T09:34:52+00:00","breadcrumb":{"@id":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/novaorg.cofb.net\/2013\/09\/13\/motxilles-escolars-millor-la-desquena-que-la-de-rodes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.cofb.org\/"},{"@type":"ListItem","position":2,"name":"Motxilles escolars: millor la d&#8217;esquena que la de rodes"}]},{"@type":"WebSite","@id":"https:\/\/www.cofb.org\/#website","url":"https:\/\/www.cofb.org\/","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","description":"","publisher":{"@id":"https:\/\/www.cofb.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cofb.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.cofb.org\/#organization","name":"Col\u00b7legi de Farmac\u00e8utics de Barcelona","url":"https:\/\/www.cofb.org\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","contentUrl":"https:\/\/www.cofb.org\/wp-content\/uploads\/2023\/11\/cropped-Logotip-COFB.png","width":500,"height":105,"caption":"Col\u00b7legi de Farmac\u00e8utics de Barcelona"},"image":{"@id":"https:\/\/www.cofb.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/farmaceuticsbcn\/","https:\/\/twitter.com\/farmaceuticsbcn","https:\/\/www.instagram.com\/farmaceuticsbcn\/","https:\/\/www.linkedin.com\/company\/farmaceuticsbcn\/"]},{"@type":"Person","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/22ed7eea88da74b0fa4d3154ad87ffcb","name":"wpAdminCofbOrg","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.cofb.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1721b20b3b8ca882c3b56ec6c978c594fff670e40c0718e9190eaeeb76aae7d8?s=96&d=mm&r=g","caption":"wpAdminCofbOrg"},"sameAs":["http:\/\/192.168.64.122\/wordpress"],"url":"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"wpAdminCofbOrg","author_link":"https:\/\/www.cofb.org\/ca\/author\/wpadmincofborg\/"},"uagb_comment_info":0,"uagb_excerpt":"La tornada a l\u2019escola ja ha arribat i aix\u00f2 suposa per als nens portar una motxilla plena de llibres, llibretes, carpetes, material escolar etc. una c\u00e0rrega de vegades excessiva que pot generar problemes d\u2019esquena. Segons estudis realitzats, s\u2019aconsella m\u00e9s l\u2019\u00fas de la motxilla d\u2019esquena que el de la motxilla de [&hellip;]","_links":{"self":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts\/68798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/comments?post=68798"}],"version-history":[{"count":0,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/posts\/68798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/media?parent=68798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/categories?post=68798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cofb.org\/ca\/wp-json\/wp\/v2\/tags?post=68798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}